{"id":20959,"date":"2026-02-02T15:00:36","date_gmt":"2026-02-02T20:00:36","guid":{"rendered":"https:\/\/loigica.com\/es\/?page_id=20959"},"modified":"2026-07-02T11:31:18","modified_gmt":"2026-07-02T15:31:18","slug":"visa-h-1b1","status":"publish","type":"page","link":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/","title":{"rendered":"Visa H-1B1 | Profesionales de Chile y Singapur"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20959\" class=\"elementor elementor-20959\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23a8ba70 e-flex e-con-boxed e-con e-parent\" data-id=\"23a8ba70\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1a282a28 e-con-full e-flex e-con e-child\" data-id=\"1a282a28\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e32725e elementor-widget elementor-widget-elementskit-heading\" data-id=\"3e32725e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \"><span>Visa H-1B1<\/span> para profesionales de Chile y Singapur<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p><span style=\"font-weight: 400\">La visa H-1B1 permite a ciudadanos de Chile y Singapur trabajar legalmente en Estados Unidos en ocupaciones profesionales, sin necesidad de participar en la loter\u00eda H-1B y con un proceso mucho m\u00e1s \u00e1gil y accesible para empleadores y candidatos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Es ideal para ingenieros, analistas, profesionales STEM, especialistas en negocios, tecnolog\u00eda, finanzas, log\u00edstica, ciencias, consultor\u00eda, ingenier\u00eda, salud, energ\u00eda y roles profesionales que requieren formaci\u00f3n o experiencia avanzada.<\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t<div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46ab06c7 e-con-full e-flex e-con e-child\" data-id=\"46ab06c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43ffef08 elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"43ffef08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#contact-form\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tConsulta con un abogado ahora\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-083a608 elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"083a608\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/loigica.com\/immigration\/employment-visas\/h-1b1-visa\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\t<i class=\"fas fa-globe\"><\/i>Ingles\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cb6cc34 e-flex e-con-boxed e-con e-parent\" data-id=\"5cb6cc34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-78ba1133 e-con-full e-flex e-con e-child\" data-id=\"78ba1133\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-484f76d2 elementor-widget__width-auto elementor-widget elementor-widget-elementskit-heading\" data-id=\"484f76d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div><h2 class=\"ekit-heading--title elementskit-section-title \">Qu\u00e9 es la <span>visa H-1B1<\/span><\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5698a78a elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"5698a78a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La H-1B1 es una subcategor\u00eda del programa H-1B exclusiva para ciudadanos de Chile y Singapur.<\/span><\/p><p><span style=\"font-weight: 400;\">Permite obtener autorizaci\u00f3n laboral en EE. UU. sin loter\u00eda y con requisitos m\u00e1s flexibles que la H-1B tradicional.<\/span><\/p><p><span style=\"font-weight: 400;\">A diferencia de otras visas laborales, la H-1B1 puede tramitarse directamente en el consulado de EE. UU. del pa\u00eds de origen y puede renovarse indefinidamente mientras se mantenga la oferta de empleo.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-476fc9c0 e-flex e-con-boxed e-con e-parent\" data-id=\"476fc9c0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7565e8fd elementor-widget elementor-widget-elementskit-heading\" data-id=\"7565e8fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \"><span>C\u00f3mo obtener<\/span> una visa de trabajo a trav\u00e9s de la H-1B1<\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-star elementskit-bullet\"><div class=\"elementskit-border-star elementskit-bullet\"><\/div><\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p><span style=\"font-weight: 400\">Para aplicar a la H-1B1 es necesario demostrar:<\/span><\/p>\n<p><span style=\"font-weight: 400\">- Que el empleo ofrecido es una ocupaci\u00f3n especializada (\u201cspecialty occupation\u201d).<\/span><\/p>\n<p><span style=\"font-weight: 400\">- El candidato posee t\u00edtulo universitario o experiencia equivalente para desempe\u00f1ar el rol.<\/span><\/p>\n<p><span style=\"font-weight: 400\">- Que el empleador en EE. UU. cumple con condiciones salariales y laborales certificadas ante el Departamento de Labor (LCA).<\/span><\/p>\n<p><span style=\"font-weight: 400\">En <strong>LOIGICA<\/strong> te guiamos en todo el proceso, desde la evaluaci\u00f3n profesional, preparaci\u00f3n de documentos, estrategia legal y presentaci\u00f3n en consulado o frontera.<\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7a5d6d elementor-widget elementor-widget-image\" data-id=\"6d7a5d6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/photo-1522202176988-66273c2fd55f-768x512.avif\" class=\"attachment-medium_large size-medium_large wp-image-21409\" alt=\"visa o-1\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/photo-1522202176988-66273c2fd55f-768x512.avif 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/photo-1522202176988-66273c2fd55f-300x200.avif 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/photo-1522202176988-66273c2fd55f-1024x683.avif 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/photo-1522202176988-66273c2fd55f.avif 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68532cba e-con-full e-flex e-con e-parent\" data-id=\"68532cba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6fe96002 e-con-full e-flex e-con e-child\" data-id=\"6fe96002\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3266bc51 elementor-widget elementor-widget-image\" data-id=\"3266bc51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/8fa4dd09-7e12-4bc0-9afb-dcb7588ff5ad-768x768.webp\" class=\"attachment-medium_large size-medium_large wp-image-20519\" alt=\"visa o-1\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/8fa4dd09-7e12-4bc0-9afb-dcb7588ff5ad-768x768.webp 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/8fa4dd09-7e12-4bc0-9afb-dcb7588ff5ad-300x300.webp 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/8fa4dd09-7e12-4bc0-9afb-dcb7588ff5ad-150x150.webp 150w, https:\/\/loigica.com\/es\/wp-content\/uploads\/8fa4dd09-7e12-4bc0-9afb-dcb7588ff5ad.webp 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48b188f6 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"48b188f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accordion-4\" id=\"accordion-6a97c56dc8b13\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-48b188f6\">\n                        <a href=\"#collapse-bc228306a97c56dc8b13\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bc228306a97c56dc8b13\" aria-expanded=\"true\" aria-controls=\"Collapse-bc228306a97c56dc8b13\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i class=\"fas fa-angle-double-left\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-arrow-right\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Beneficios de la H-1B1<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bc228306a97c56dc8b13\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-48b188f6\" data-parent=\"#accordion-6a97c56dc8b13\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ul><li><span style=\"font-weight: 400\">No requiere loter\u00eda: acceso directo.<\/span><\/li><li><span style=\"font-weight: 400\">Tr\u00e1mite r\u00e1pido y simplificado.<\/span><\/li><li><span style=\"font-weight: 400\">Elegible para ciudadanos chilenos y singapurenses.<\/span><\/li><li><span style=\"font-weight: 400\">Vigencia inicial de 18 meses, renovable indefinidamente.<\/span><\/li><li><span style=\"font-weight: 400\">Posibilidad de transici\u00f3n a H-1B o a Green Card.<\/span><\/li><li><span style=\"font-weight: 400\">Menor carga administrativa para empleadores.<\/span><\/li><li><span style=\"font-weight: 400\">Ideal para roles STEM, ingenier\u00eda, consultor\u00eda y profesionales altamente capacitados.<\/span><\/li><\/ul>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-48b188f6\">\n                        <a href=\"#collapse-8417e716a97c56dc8b13\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-8417e716a97c56dc8b13\" aria-expanded=\"false\" aria-controls=\"Collapse-8417e716a97c56dc8b13\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i class=\"fas fa-angle-double-left\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-arrow-right\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">Requisitos para obtener la H-1B1<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-8417e716a97c56dc8b13\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-48b188f6\" data-parent=\"#accordion-6a97c56dc8b13\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">Para solicitar la H-1B1 se debe demostrar:<\/span><\/p><ul><li><span style=\"font-weight: 400\">Ciudadan\u00eda de Chile o Singapur.<\/span><\/li><li><span style=\"font-weight: 400\">Oferta laboral en EE. UU. en una ocupaci\u00f3n profesional.<\/span><\/li><li><span style=\"font-weight: 400\">T\u00edtulo universitario relacionado o experiencia equivalente (3 a\u00f1os = 1 a\u00f1o acad\u00e9mico).<\/span><\/li><li><span style=\"font-weight: 400\">LCA aprobada por el Departamento de Labor.<\/span><\/li><li><span style=\"font-weight: 400\">Sustento documental del empleador y del cargo ofrecido.<\/span><\/li><li><span style=\"font-weight: 400\">Evidencia de experiencia profesional, certificaciones, trayectoria o especialidad.<\/span><\/li><\/ul><p><span style=\"font-weight: 400\">La solicitud se presenta directamente en consulado mediante el formulario DS-160 y entrevista consular.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-48b188f6\">\n                        <a href=\"#collapse-3dad4e06a97c56dc8b13\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3dad4e06a97c56dc8b13\" aria-expanded=\"false\" aria-controls=\"Collapse-3dad4e06a97c56dc8b13\">\n                                                            <div class=\"ekit_accordion_icon_left_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i class=\"fas fa-angle-double-left\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-arrow-right\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                            <span class=\"ekit-accordion-title\">C\u00f3mo LOIGICA acompa\u00f1a procesos H-1B1<\/span>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3dad4e06a97c56dc8b13\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-48b188f6\" data-parent=\"#accordion-6a97c56dc8b13\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ul><li><span style=\"font-weight: 400\">Evaluaci\u00f3n completa de elegibilidad del candidato y del empleador.<\/span><\/li><li><span style=\"font-weight: 400\">Preparaci\u00f3n de la estrategia legal y ocupacional (\u201cspecialty occupation\u201d).<\/span><\/li><li><span style=\"font-weight: 400\">Armado de la LCA y documentaci\u00f3n corporativa.<\/span><\/li><li><span style=\"font-weight: 400\">Elaboraci\u00f3n de evidencia profesional, CV estructurado y soporte t\u00e9cnico.<\/span><\/li><li><span style=\"font-weight: 400\">Preparaci\u00f3n para la entrevista consular.<\/span><\/li><li><span style=\"font-weight: 400\">Acompa\u00f1amiento en renovaciones, cambios y transici\u00f3n a H-1B o Green Card.<\/span><\/li><li><span style=\"font-weight: 400\">Seguimiento legal integral durante todo el proceso migratorio.<\/span><\/li><\/ul>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e833eb3 e-flex e-con-boxed e-con e-child\" data-id=\"7e833eb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-720bd298 elementor-widget__width-auto elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"720bd298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#contact-form\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\t<i class=\"far fa-arrow-alt-circle-right\"><\/i>Evaluar elegibilidad H-1B1\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f213f9a e-flex e-con-boxed e-con e-parent\" data-id=\"5f213f9a\" data-element_type=\"container\" data-e-type=\"container\" id=\"xs_cta_style_2\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-37c2d262 e-con-full e-flex e-con e-child\" data-id=\"37c2d262\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-464a4290 elementor-widget elementor-widget-elementskit-heading\" data-id=\"464a4290\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Da el siguiente paso hacia tu <span>H-1B1.<\/span><\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59f42479 elementor-align-left elementor-align--mobilecenter elementor-widget elementor-widget-elementskit-button\" data-id=\"59f42479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#contact-form\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tConversemos hoy\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56832980 e-con-full e-flex e-con e-child\" data-id=\"56832980\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c3433b9 elementor-widget elementor-widget-image\" data-id=\"4c3433b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"411\" height=\"354\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Loigica-Silver.png\" class=\"attachment-large size-large wp-image-21458\" alt=\"\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Loigica-Silver.png 411w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Loigica-Silver-300x258.png 300w\" sizes=\"(max-width: 411px) 100vw, 411px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18920734 e-flex e-con-boxed e-con e-parent\" data-id=\"18920734\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cd432fa e-con-full e-flex e-con e-child\" data-id=\"cd432fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e43e544 elementor-widget elementor-widget-elementskit-heading\" data-id=\"7e43e544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Preguntas frecuentes <span>sobre la H-1B1<\/span><\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b0772c0 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"2b0772c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a97c56dce8ec\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-2b0772c0\">\n                        <a href=\"#collapse-14514dc6a97c56dce8ec\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-14514dc6a97c56dce8ec\" aria-expanded=\"true\" aria-controls=\"Collapse-14514dc6a97c56dce8ec\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQu\u00e9 tipo de profesional puede aplicar a la H-1B1?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.19995 16.5V0.5H8.79995V16.5H7.19995Z\" fill=\"#3D3D3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 7.69995L16 7.69995L16 9.29995L-2.78554e-07 9.29995L-2.08616e-07 7.69995Z\" fill=\"#3D3D3D\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"3\" viewBox=\"0 0 16 3\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 0.499999L16 0.5L16 2.5L-2.78554e-07 2.5L-2.08616e-07 0.499999Z\" fill=\"#675AFE\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-14514dc6a97c56dce8ec\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-2b0772c0\" data-parent=\"#accordion-6a97c56dce8ec\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">Ingenieros, analistas, profesionales STEM, especialistas en negocios, finanzas, TI, ciencias, log\u00edstica, consultor\u00eda y roles que requieren formaci\u00f3n avanzada.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-2b0772c0\">\n                        <a href=\"#collapse-35c8fe46a97c56dce8ec\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-35c8fe46a97c56dce8ec\" aria-expanded=\"false\" aria-controls=\"Collapse-35c8fe46a97c56dce8ec\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfNecesito una oferta laboral para aplicar?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.19995 16.5V0.5H8.79995V16.5H7.19995Z\" fill=\"#3D3D3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 7.69995L16 7.69995L16 9.29995L-2.78554e-07 9.29995L-2.08616e-07 7.69995Z\" fill=\"#3D3D3D\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"3\" viewBox=\"0 0 16 3\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 0.499999L16 0.5L16 2.5L-2.78554e-07 2.5L-2.08616e-07 0.499999Z\" fill=\"#675AFE\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-35c8fe46a97c56dce8ec\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-2b0772c0\" data-parent=\"#accordion-6a97c56dce8ec\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">S\u00ed. La H-1B1 requiere una oferta laboral profesional de un empleador de EE. UU.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-2b0772c0\">\n                        <a href=\"#collapse-c29457c6a97c56dce8ec\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-c29457c6a97c56dce8ec\" aria-expanded=\"false\" aria-controls=\"Collapse-c29457c6a97c56dce8ec\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfLa H-1B1 tiene loter\u00eda?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.19995 16.5V0.5H8.79995V16.5H7.19995Z\" fill=\"#3D3D3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 7.69995L16 7.69995L16 9.29995L-2.78554e-07 9.29995L-2.08616e-07 7.69995Z\" fill=\"#3D3D3D\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"3\" viewBox=\"0 0 16 3\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 0.499999L16 0.5L16 2.5L-2.78554e-07 2.5L-2.08616e-07 0.499999Z\" fill=\"#675AFE\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-c29457c6a97c56dce8ec\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-2b0772c0\" data-parent=\"#accordion-6a97c56dce8ec\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">No. Es una v\u00eda directa disponible para chilenos y singapurenses.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-2b0772c0\">\n                        <a href=\"#collapse-f0f54c16a97c56dce8ec\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f0f54c16a97c56dce8ec\" aria-expanded=\"false\" aria-controls=\"Collapse-f0f54c16a97c56dce8ec\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1nto dura la visa H-1B1?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.19995 16.5V0.5H8.79995V16.5H7.19995Z\" fill=\"#3D3D3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 7.69995L16 7.69995L16 9.29995L-2.78554e-07 9.29995L-2.08616e-07 7.69995Z\" fill=\"#3D3D3D\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"3\" viewBox=\"0 0 16 3\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 0.499999L16 0.5L16 2.5L-2.78554e-07 2.5L-2.08616e-07 0.499999Z\" fill=\"#675AFE\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f0f54c16a97c56dce8ec\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-2b0772c0\" data-parent=\"#accordion-6a97c56dce8ec\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">Tiene una vigencia de 18 meses y puede renovarse indefinidamente.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-2b0772c0\">\n                        <a href=\"#collapse-d9162c96a97c56dce8ec\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-d9162c96a97c56dce8ec\" aria-expanded=\"false\" aria-controls=\"Collapse-d9162c96a97c56dce8ec\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo cambiar de empleador?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.19995 16.5V0.5H8.79995V16.5H7.19995Z\" fill=\"#3D3D3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 7.69995L16 7.69995L16 9.29995L-2.78554e-07 9.29995L-2.08616e-07 7.69995Z\" fill=\"#3D3D3D\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"3\" viewBox=\"0 0 16 3\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 0.499999L16 0.5L16 2.5L-2.78554e-07 2.5L-2.08616e-07 0.499999Z\" fill=\"#675AFE\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-d9162c96a97c56dce8ec\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-2b0772c0\" data-parent=\"#accordion-6a97c56dce8ec\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">S\u00ed, mediante nuevo proceso de LCA y solicitud.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-2b0772c0\">\n                        <a href=\"#collapse-a7c13cb6a97c56dce8ec\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-a7c13cb6a97c56dce8ec\" aria-expanded=\"false\" aria-controls=\"Collapse-a7c13cb6a97c56dce8ec\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo incluir a mi familia?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.19995 16.5V0.5H8.79995V16.5H7.19995Z\" fill=\"#3D3D3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 7.69995L16 7.69995L16 9.29995L-2.78554e-07 9.29995L-2.08616e-07 7.69995Z\" fill=\"#3D3D3D\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"3\" viewBox=\"0 0 16 3\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 0.499999L16 0.5L16 2.5L-2.78554e-07 2.5L-2.08616e-07 0.499999Z\" fill=\"#675AFE\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-a7c13cb6a97c56dce8ec\" class=\" collapse\" aria-labelledby=\"primaryHeading-5-2b0772c0\" data-parent=\"#accordion-6a97c56dce8ec\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">S\u00ed. C\u00f3nyuge e hijos menores pueden obtener visas dependientes H-4.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-2b0772c0\">\n                        <a href=\"#collapse-287d23b6a97c56dce8ec\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-287d23b6a97c56dce8ec\" aria-expanded=\"false\" aria-controls=\"Collapse-287d23b6a97c56dce8ec\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo cambiar de H-1B1 a Green Card?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.19995 16.5V0.5H8.79995V16.5H7.19995Z\" fill=\"#3D3D3D\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 7.69995L16 7.69995L16 9.29995L-2.78554e-07 9.29995L-2.08616e-07 7.69995Z\" fill=\"#3D3D3D\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"3\" viewBox=\"0 0 16 3\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-2.08616e-07 0.499999L16 0.5L16 2.5L-2.78554e-07 2.5L-2.08616e-07 0.499999Z\" fill=\"#675AFE\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-287d23b6a97c56dce8ec\" class=\" collapse\" aria-labelledby=\"primaryHeading-6-2b0772c0\" data-parent=\"#accordion-6a97c56dce8ec\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><span style=\"font-weight: 400\">S\u00ed. Muchos candidatos transicionan a H-1B tradicional o EB-2\/EB-3 para obtener residencia.<\/span><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b4cfefa e-con-full e-flex e-con e-parent\" data-id=\"6b4cfefa\" data-element_type=\"container\" data-e-type=\"container\" id=\"contact-form\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-203a338 e-con-full e-flex e-con e-child\" data-id=\"203a338\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22704cfb elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"22704cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Obt\u00e9n asesor\u00eda legal para tu proceso H-1B1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-662e3210 elementor-widget elementor-widget-text-editor\" data-id=\"662e3210\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"font-weight: 400;\">La visa H-1B1 requiere claridad profesional, coherencia en el cargo ofrecido y evidencia precisa que demuestre que el rol califica como \u201cspecialty occupation\u201d.<\/span><\/h4><h4><span style=\"font-weight: 400;\">Errores comunes como salarios incorrectos, descripciones gen\u00e9ricas, LCA mal presentada o falta de evidencia profesional pueden resultar en rechazos o demoras.<\/span><\/h4><h4><span style=\"font-weight: 400;\">Nuestro equipo construye tu caso con el est\u00e1ndar legal que USCIS y el Departamento de Estado requieren.<\/span><\/h4><h4><b>Agenda tu primera consulta GRATIS.<\/b><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a04160d e-con-full e-flex e-con e-child\" data-id=\"5a04160d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b226ef2 elementor-widget elementor-widget-hubspot-form\" data-id=\"7b226ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hubspot-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t\t\t\t<script>\n\t\t\t\t\t\t\twindow.hsFormsOnReady = window.hsFormsOnReady || [];\n\t\t\t\t\t\t\twindow.hsFormsOnReady.push(()=>{\n\t\t\t\t\t\t\t\thbspt.forms.create({\n\t\t\t\t\t\t\t\t\tportalId: 1653096,\n\t\t\t\t\t\t\t\t\tformId: \"b9943b6a-96e6-460e-a8ff-e03eb8d791bb\",\n\t\t\t\t\t\t\t\t\ttarget: \"#hbspt-form-1788336861000-4990522911\",\n\t\t\t\t\t\t\t\t\tregion: \"na1\",\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t})});\n\t\t\t\t\t\t<\/script>\n\t\t\t\t\t\t<div class=\"hbspt-form\" id=\"hbspt-form-1788336861000-4990522911\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Visa H-1B1 para profesionales de Chile y Singapur La visa H-1B1 permite a ciudadanos de Chile y Singapur trabajar legalmente en Estados Unidos en ocupaciones profesionales, sin necesidad de participar en la loter\u00eda H-1B y con un proceso mucho m\u00e1s \u00e1gil y accesible para empleadores y candidatos. Es ideal para ingenieros, analistas, profesionales STEM, especialistas [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"parent":21770,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"class_list":["post-20959","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visa H-1B1 | Profesionales de Chile y Singapur | Loigica<\/title>\n<meta name=\"description\" content=\"Visa H-1B1 para profesionales de Chile y Singapur que desean trabajar en Estados Unidos. Requisitos y proceso migratorio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visa H-1B1 | Profesionales de Chile y Singapur | Loigica\" \/>\n<meta property=\"og:description\" content=\"Visa H-1B1 para profesionales de Chile y Singapur que desean trabajar en Estados Unidos. Requisitos y proceso migratorio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/\" \/>\n<meta property=\"og:site_name\" content=\"Loigica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loigica\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T15:31:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/contact-us.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Loigica\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/visa-h-1b1\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/visa-h-1b1\\\/\",\"name\":\"Visa H-1B1 | Profesionales de Chile y Singapur | Loigica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/visa-h-1b1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/visa-h-1b1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/photo-1522202176988-66273c2fd55f-768x512.avif\",\"datePublished\":\"2026-02-02T20:00:36+00:00\",\"dateModified\":\"2026-07-02T15:31:18+00:00\",\"description\":\"Visa H-1B1 para profesionales de Chile y Singapur que desean trabajar en Estados Unidos. Requisitos y proceso migratorio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/visa-h-1b1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/visa-h-1b1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/visa-h-1b1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/photo-1522202176988-66273c2fd55f-768x512.avif\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/photo-1522202176988-66273c2fd55f-768x512.avif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/visa-h-1b1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inmigraci\u00f3n\",\"item\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visas de Empleo | Trabajar legalmente en Estados Unidos\",\"item\":\"https:\\\/\\\/loigica.com\\\/es\\\/inmigracion\\\/visas-empleo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Visa H-1B1 | Profesionales de Chile y Singapur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"name\":\"Loigica\",\"description\":\"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM\",\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loigica.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\",\"name\":\"Loigica\",\"alternateName\":\"Loigica Immigration Attorneys\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"width\":369,\"height\":317,\"caption\":\"Loigica\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loigica\\\/\",\"https:\\\/\\\/x.com\\\/Loigica\",\"https:\\\/\\\/www.instagram.com\\\/loigica\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Loigica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visa H-1B1 | Profesionales de Chile y Singapur | Loigica","description":"Visa H-1B1 para profesionales de Chile y Singapur que desean trabajar en Estados Unidos. Requisitos y proceso migratorio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/","og_locale":"es_ES","og_type":"article","og_title":"Visa H-1B1 | Profesionales de Chile y Singapur | Loigica","og_description":"Visa H-1B1 para profesionales de Chile y Singapur que desean trabajar en Estados Unidos. Requisitos y proceso migratorio.","og_url":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/","og_site_name":"Loigica","article_publisher":"https:\/\/www.facebook.com\/loigica\/","article_modified_time":"2026-07-02T15:31:18+00:00","og_image":[{"width":600,"height":900,"url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/contact-us.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Loigica","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/","url":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/","name":"Visa H-1B1 | Profesionales de Chile y Singapur | Loigica","isPartOf":{"@id":"https:\/\/loigica.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/#primaryimage"},"image":{"@id":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/photo-1522202176988-66273c2fd55f-768x512.avif","datePublished":"2026-02-02T20:00:36+00:00","dateModified":"2026-07-02T15:31:18+00:00","description":"Visa H-1B1 para profesionales de Chile y Singapur que desean trabajar en Estados Unidos. Requisitos y proceso migratorio.","breadcrumb":{"@id":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/#primaryimage","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/photo-1522202176988-66273c2fd55f-768x512.avif","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/photo-1522202176988-66273c2fd55f-768x512.avif"},{"@type":"BreadcrumbList","@id":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/visa-h-1b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inmigraci\u00f3n","item":"https:\/\/loigica.com\/es\/inmigracion\/"},{"@type":"ListItem","position":2,"name":"Visas de Empleo | Trabajar legalmente en Estados Unidos","item":"https:\/\/loigica.com\/es\/inmigracion\/visas-empleo\/"},{"@type":"ListItem","position":3,"name":"Visa H-1B1 | Profesionales de Chile y Singapur"}]},{"@type":"WebSite","@id":"https:\/\/loigica.com\/es\/#website","url":"https:\/\/loigica.com\/es\/","name":"Loigica","description":"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM","publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loigica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loigica.com\/es\/#organization","name":"Loigica","alternateName":"Loigica Immigration Attorneys","url":"https:\/\/loigica.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","width":369,"height":317,"caption":"Loigica"},"image":{"@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loigica\/","https:\/\/x.com\/Loigica","https:\/\/www.instagram.com\/loigica\/","https:\/\/www.youtube.com\/@Loigica\/"]}]}},"_links":{"self":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/pages\/20959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/comments?post=20959"}],"version-history":[{"count":20,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/pages\/20959\/revisions"}],"predecessor-version":[{"id":24381,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/pages\/20959\/revisions\/24381"}],"up":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/pages\/21770"}],"wp:attachment":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media?parent=20959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}