{"id":11910,"date":"2024-02-16T07:06:25","date_gmt":"2024-02-16T12:06:25","guid":{"rendered":"https:\/\/loigica.com\/es\/?p=11910"},"modified":"2026-01-27T11:14:56","modified_gmt":"2026-01-27T16:14:56","slug":"articulos-formulario-i-40-hijos","status":"publish","type":"post","link":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/","title":{"rendered":"\u00bfPueden mis hijos estudiar mientras aprueban mi I-140?"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11910\" class=\"elementor elementor-11910\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-348d71d elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"348d71d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d696f5e\" data-id=\"2d696f5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-60067d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60067d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ea9fa87\" data-id=\"ea9fa87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-74f9e27\" data-id=\"74f9e27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63fa0b0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63fa0b0e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45cfd7f3\" data-id=\"45cfd7f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46c662a9 elementor-widget elementor-widget-text-editor\" data-id=\"46c662a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em><span class=\"TextRun SCXW160429880 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW160429880 BCX4\">I-140<\/span><\/span><span class=\"EOP SCXW160429880 BCX4\" data-ccp-props=\"{&quot;335559739&quot;:0}\">\u00a0<\/span> &#8211; 9 \u00a0minutos de lectura\u00a0<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b941bcf elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b941bcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 72 72\" style=\"enable-background:new 0 0 72 72;\" xml:space=\"preserve\"><g id=\"Capa_12\">\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<g>\t\t\t\t\t\t<path d=\"M40.3,34.5c0.7-0.1,1.4-0.2,2.1-0.2c5.7,0.3,7.1,5.4,6.2,8.2c-1.7,4.9-4.1,5.5-6.5,11c-1.8,4.1-3,8.9-0.5,15.6h14.7       c-10.2-11.5-0.1-29.2,15.4-25.8c-1.3-9.6-10.2-13.2-16.5-11.6c-1-2.6-5.4-8.9-14-7.7C18.8,27.3,14.5,10,16,2.9       C2,16.8,12.9,39.3,40.3,34.5z\"><\/path>\t\t\t\t\t<\/g>\t\t\t\t<\/g>\t\t\t<\/g>\t\t\t<path d=\"M31.4,42.3C7.5,46.5,2.2,28.5,2.6,23.1C-4,35.2,4,55.4,21.8,51.2c2.5-0.8,3.5,1.9,1.7,3c-7.6,4.4-9.3,9.9-9.7,14.9    c0,0,14.4,0,14.4,0c-1-11.7,5.5-16.4,7.8-18.6C39.9,46.4,36.4,41.4,31.4,42.3z\"><\/path>\t\t<\/g>\t<\/g><\/g><g id=\"Capa_11\"><\/g><g id=\"Capa_10\"><\/g><g id=\"Capa_5\"><\/g><g id=\"Capa_8\"><\/g><g id=\"Capa_7\"><\/g><g id=\"Capa_6\"><\/g><g id=\"Capa_4\"><\/g><g id=\"Capa_3\"><\/g><g id=\"Capa_2\"><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEn pocas palabras\u2026\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLa decisi\u00f3n de Plyler v. Doe de 1982 asegura que todos los ni\u00f1os, independientemente de su estatus migratorio, tienen acceso a la educaci\u00f3n p\u00fablica. Este derecho se mantiene mientras tu petici\u00f3n I-140 est\u00e1 en proceso. Las escuelas no pueden negar la inscripci\u00f3n de tus hijos bas\u00e1ndose en su estatus migratorio o en el tuyo.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c84d7fa elementor-widget elementor-widget-text-editor\" data-id=\"1c84d7fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"NormalTextRun SCXW202284742 BCX4\">\u00ab\u00bf<\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">Pueden <\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">mis<\/span><span class=\"NormalTextRun SCXW202284742 BCX4\"> hijos continuar su educaci\u00f3n mientras esper<\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">o<\/span><span class=\"NormalTextRun SCXW202284742 BCX4\"> la aprobaci\u00f3n del formulario I-140?<\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">\u00bb<\/span><span class=\"NormalTextRun SCXW202284742 BCX4\"> es una pregunta com\u00fan <\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">p<\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">ara muchas familias en proceso de inmigraci\u00f3n. Entender las normas y <\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">los <\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">derechos educativos en <\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">los <\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">Estados Unidos puede ser <\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">una tarea <\/span><span class=\"NormalTextRun SCXW202284742 BCX4\">abrumadora, pero es fundamental saber que la educaci\u00f3n de tus hijos no tiene por qu\u00e9 detenerse debido a tr\u00e1mites migratorios.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c1805 elementor-widget elementor-widget-text-editor\" data-id=\"e4c1805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400; text-align: left;\"><span class=\"NormalTextRun SCXW211074248 BCX4\">En este proceso, garantizar la continuidad educativa de los menores<\/span><span class=\"NormalTextRun SCXW211074248 BCX4\"> suele estar entre las prioridades de muchos padres y madres migrantes<\/span><span class=\"NormalTextRun SCXW211074248 BCX4\">. <\/span><span class=\"NormalTextRun SCXW211074248 BCX4\">Y l<\/span><span class=\"NormalTextRun SCXW211074248 BCX4\">a legislaci\u00f3n estadounidense reconoce la importancia de la educaci\u00f3n como un pilar para el desarrollo integral de los ni\u00f1os y j\u00f3venes, independientemente de su origen o estatus legal.<\/span><span class=\"NormalTextRun SCXW211074248 BCX4\"> Por lo menos, esto ha sido as\u00ed desde 1982<\/span><span class=\"NormalTextRun SCXW211074248 BCX4\">, gracias a la resoluci\u00f3n de la Corte Constitucional en <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SpellingErrorHighlight SCXW211074248 BCX4\">Plyler<\/span><span class=\"NormalTextRun SCXW211074248 BCX4\"> v. <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW211074248 BCX4\">Doe<\/span><span class=\"NormalTextRun SCXW211074248 BCX4\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e60c4f elementor-widget elementor-widget-text-editor\" data-id=\"3e60c4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400; text-align: left;\">\u00a0<span class=\"TextRun SCXW158798728 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW158798728 BCX4\">E<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">n e<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">ste blog<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">,<\/span> <span class=\"NormalTextRun SCXW158798728 BCX4\">queremos<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\"> ofrecer<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">te<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\"> algo de<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\"> claridad <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">sobre el<\/span> <span class=\"NormalTextRun SCXW158798728 BCX4\">derecho<\/span> <span class=\"NormalTextRun SCXW158798728 BCX4\">a la educaci\u00f3n<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\"> en <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">los <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">Estados Unidos <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">y responder <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">a <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">esta duda <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">(y otras) <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">que <\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">tanto<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\"> nos ha llegado<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">.<\/span><span class=\"NormalTextRun SCXW158798728 BCX4\">\u00a0<\/span><\/span><span class=\"EOP SCXW158798728 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e81036 elementor-widget elementor-widget-text-editor\" data-id=\"3e81036\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Entendamos el Formulario I-140<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b93f245 elementor-widget elementor-widget-text-editor\" data-id=\"b93f245\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW137729562 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW137729562 BCX4\">El <\/span><span class=\"NormalTextRun SCXW137729562 BCX4\">f<\/span><span class=\"NormalTextRun SCXW137729562 BCX4\">ormulario I-140 es tu llave hacia un futuro estable en Estados Unidos<\/span><span class=\"NormalTextRun SCXW137729562 BCX4\"> c<\/span><span class=\"NormalTextRun SCXW137729562 BCX4\">omo <\/span><span class=\"NormalTextRun SCXW137729562 BCX4\">trabajador <\/span><span class=\"NormalTextRun SCXW137729562 BCX4\">inmigrante buscando\u00a0<\/span><\/span><span class=\"TextRun SCXW137729562 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW137729562 BCX4\"><a href=\"https:\/\/loigica.com\/es\/residencia-americana-green-card\/\" target=\"_blank\" rel=\"noopener\">residencia permanente.<\/a>\u00a0<\/span><span class=\"NormalTextRun SCXW137729562 BCX4\">Antes de nada, queremos<\/span> <span class=\"NormalTextRun SCXW137729562 BCX4\">recordarte todo<\/span><span class=\"NormalTextRun SCXW137729562 BCX4\"> lo que necesitas saber sobre e<\/span><span class=\"NormalTextRun SCXW137729562 BCX4\">ste formulario:<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9d596b elementor-widget elementor-widget-heading\" data-id=\"e9d596b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es el formulario I-140?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d60f81 elementor-widget elementor-widget-text-editor\" data-id=\"7d60f81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"NormalTextRun SCXW165906298 BCX4\">El I-140 es una petici\u00f3n de inmigraci\u00f3n para trabajadores extranjeros. Lo presenta tu empleador para demostrar que eres indispensable para un trabajo en <\/span><span class=\"NormalTextRun SCXW165906298 BCX4\">los Estados Unidos.<\/span><span class=\"NormalTextRun SCXW165906298 BCX4\"> Este formulario es el primer paso hacia <\/span><span class=\"NormalTextRun SCXW165906298 BCX4\">la Green Card<\/span><span class=\"NormalTextRun SCXW165906298 BCX4\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-daef366 elementor-widget elementor-widget-heading\" data-id=\"daef366\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQui\u00e9n es elegible para la petici\u00f3n I-140?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80381af elementor-widget elementor-widget-text-editor\" data-id=\"80381af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW66234556 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW66234556 BCX4\">Para ser elegible, debes tener una oferta de trabajo en <\/span><span class=\"NormalTextRun SCXW66234556 BCX4\">los Estados Unidos.<\/span><span class=\"NormalTextRun SCXW66234556 BCX4\"> El puesto debe requerir habilidades especializadas y tu empleador debe estar dispuesto a patrocinar tu residencia permanente. Cada categor\u00eda de visa, como <\/span><span class=\"NormalTextRun SCXW66234556 BCX4\"><a href=\"https:\/\/loigica.com\/es\/visas-eb1-a\/\">la <\/a><\/span><\/span><span class=\"TextRun SCXW66234556 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW66234556 BCX4\"><a href=\"https:\/\/loigica.com\/es\/visas-eb1-a\/\">EB-1<\/a><\/span><\/span><span class=\"TextRun SCXW66234556 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW66234556 BCX4\">, <\/span><span class=\"NormalTextRun SCXW66234556 BCX4\">la\u00a0<\/span><\/span><span class=\"TextRun SCXW66234556 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun Superscript SCXW66234556 BCX4\" data-fontsize=\"12\"><a href=\"https:\/\/loigica.com\/es\/visas-eb2-niw\/\" target=\"_blank\" rel=\"noopener\">EB-2<\/a><\/span><\/span><span class=\"TextRun SCXW66234556 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW66234556 BCX4\">\u00a0y <\/span><span class=\"NormalTextRun SCXW66234556 BCX4\">la <\/span><\/span><a href=\"https:\/\/loigica.com\/es\/visas-de-empleo\/\"><span class=\"TextRun SCXW66234556 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW66234556 BCX4\">EB-3<\/span><\/span><\/a><span class=\"TextRun SCXW66234556 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW66234556 BCX4\">, tiene sus propios criterios de elegibilidad.<\/span><\/span><span class=\"EOP SCXW66234556 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:284,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30c4114 elementor-widget elementor-widget-heading\" data-id=\"30c4114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1l es la documentaci\u00f3n necesaria?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7be94d1 elementor-widget elementor-widget-text-editor\" data-id=\"7be94d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW237137167 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW237137167 BCX4\">La documentaci\u00f3n var\u00eda seg\u00fan la categor\u00eda de visa, pero generalmente incluye registros educativos y laborales, estados financieros del empleador, <\/span><span class=\"NormalTextRun SCXW237137167 BCX4\">la <\/span><span class=\"NormalTextRun SCXW237137167 BCX4\">carta de oferta de trabajo y, en algunos casos, <\/span><span class=\"NormalTextRun SCXW237137167 BCX4\">una\u00a0<\/span><\/span><span class=\"TextRun SCXW237137167 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun Superscript SCXW237137167 BCX4\" data-fontsize=\"12\"><a href=\"https:\/\/loigica.com\/es\/certificacion-laboral-perm\/\" target=\"_blank\" rel=\"noopener\">certificaci\u00f3n laboral<\/a><\/span><\/span><span class=\"TextRun SCXW237137167 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW237137167 BCX4\">. Estos documentos prueban tus c<\/span><span class=\"NormalTextRun SCXW237137167 BCX4\">u<\/span><span class=\"NormalTextRun SCXW237137167 BCX4\">alificaciones y la capacidad del empleador para pagarte<\/span><span class=\"NormalTextRun SCXW237137167 BCX4\">.<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e4111c elementor-widget elementor-widget-heading\" data-id=\"5e4111c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les son los tiempos de procesamiento y presentaci\u00f3n?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2685bc0 elementor-widget elementor-widget-text-editor\" data-id=\"2685bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"NormalTextRun SCXW250158275 BCX4\">El tiempo de procesamiento del I-140 puede variar. Por ejemplo, para las categor\u00edas EB-1 y EB-2, suele ser de 6 a 8 meses, mientras que<\/span> <span class=\"NormalTextRun SCXW250158275 BCX4\">puede tardar m\u00e1s<\/span><span class=\"NormalTextRun SCXW250158275 BCX4\"> para la EB-3<\/span><span class=\"NormalTextRun SCXW250158275 BCX4\">. Debes presentar el formulario en la oficina del USCIS designada, junto con la cuota requerida y la documentaci\u00f3n pertinente<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-023697a elementor-widget elementor-widget-heading\" data-id=\"023697a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 pasa despu\u00e9s de la aprobaci\u00f3n del I-140?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad89e1c elementor-widget elementor-widget-text-editor\" data-id=\"ad89e1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">\u00a0<span class=\"TextRun SCXW29339454 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW29339454 BCX4\">Tras la aprobaci\u00f3n del I-140, puedes dar el siguiente paso hacia la residencia permanente. Dependiendo de tu situaci\u00f3n, esto puede incluir el ajuste de estatus o el procesamiento consular. Tu fecha de prioridad y el estatus de tu visa actual determinar\u00e1n tus siguientes pasos.<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5aea33 elementor-widget elementor-widget-heading\" data-id=\"d5aea33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les son los derechos educativos de los ni\u00f1os y j\u00f3venes en proceso de inmigraci\u00f3n?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca76e31 elementor-widget elementor-widget-text-editor\" data-id=\"ca76e31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW123596295 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW123596295 BCX4\">Entender los derechos educativos de tus hijos mientras atraviesas el proceso de inmigraci\u00f3n es <\/span><span class=\"NormalTextRun SCXW123596295 BCX4\">muy importante<\/span><span class=\"NormalTextRun SCXW123596295 BCX4\">. Bajo\u00a0<\/span><\/span><span class=\"TextRun SCXW123596295 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun Superscript SCXW123596295 BCX4\" data-fontsize=\"12\"><a href=\"https:\/\/www.telemundo.com\/noticias\/noticias-telemundo\/inmigracion\/el-historico-caso-que-garantizo-educacion-a-los-ninos-indocumentados-c-rcna33621\" target=\"_blank\" rel=\"noopener\">la hist\u00f3rica decisi\u00f3n de Plyler v. Doe de 1982<\/a><\/span><\/span><span class=\"TextRun SCXW123596295 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW123596295 BCX4\">, todos los ni\u00f1os en <\/span><span class=\"NormalTextRun SCXW123596295 BCX4\">los <\/span><span class=\"NormalTextRun SCXW123596295 BCX4\">Estados Unidos, independientemente de su estatus migratorio, tienen el derecho a una educaci\u00f3n p\u00fablica b\u00e1sica. Esto significa que el acceso a la educaci\u00f3n no est\u00e1 limitado por la situaci\u00f3n legal de tu familia.<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf6bef elementor-widget elementor-widget-text-editor\" data-id=\"7bf6bef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"NormalTextRun SCXW126360831 BCX4\">En t\u00e9rminos pr\u00e1cticos, esta decisi\u00f3n implica <\/span><span class=\"NormalTextRun SCXW126360831 BCX4\">que l<\/span><span class=\"NormalTextRun SCXW126360831 BCX4\">as escuelas p\u00fablicas no pueden negar la inscripci\u00f3n a tu hijo bas\u00e1ndose en su estatus migratorio o <\/span><span class=\"NormalTextRun SCXW126360831 BCX4\">en <\/span><span class=\"NormalTextRun SCXW126360831 BCX4\">el tuyo. Esto <\/span><span class=\"NormalTextRun SCXW126360831 BCX4\">permite que <\/span><span class=\"NormalTextRun SCXW126360831 BCX4\">la educaci\u00f3n<\/span><span class=\"NormalTextRun SCXW126360831 BCX4\">,<\/span> <span class=\"NormalTextRun SCXW126360831 BCX4\">un derecho fundamental para el desarrollo y la integraci\u00f3n en la sociedad<\/span><span class=\"NormalTextRun SCXW126360831 BCX4\">, sea<\/span><span class=\"NormalTextRun SCXW126360831 BCX4\"> accesible para todos.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b72d984 elementor-widget elementor-widget-text-editor\" data-id=\"b72d984\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"NormalTextRun SCXW172649496 BCX4\">De todas formas, l<\/span><span class=\"NormalTextRun SCXW172649496 BCX4\">as escuelas pueden requerir cierta documentaci\u00f3n, pero siempre dentro del marco legal que protege tus derechos y los de tus hijos:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2b84a elementor-widget elementor-widget-heading\" data-id=\"5d2b84a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo es el proceso de solicitud?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c3f651 premium-type-column elementor-widget elementor-widget-premium-icon-list\" data-id=\"1c3f651\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;rbadges_repeater&quot;:[]}\" data-widget_type=\"premium-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<ul class=\"premium-bullet-list-box\">\n\t\t\n\t\t\t<li class=\"premium-bullet-list-content elementor-repeater-item-ca007c8\">\n\t\t\t\t<div class=\"premium-bullet-list-text\">\n\t\t\t\t\t\t\t\t<div class=\"premium-bullet-list-wrapper\">\n\t\t\t\t\t<div class=\"premium-drawable-icon\"><i class=\"premium-svg-nodraw far fa-hand-point-up\" aria-hidden=\"true\"><\/i><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"premium-bullet-list-text-wrapper\">\n\t\t\t\t\t<span class=\"premium-bullet-text\" data-text=\" Prueba de residencia en el distrito escolar: Las escuelas pueden solicitar documentos que prueben que vives dentro de sus l\u00edmites. Esto puede incluir facturas de servicios, contratos de arrendamiento o declaraciones juradas. \">  Prueba de residencia en el distrito escolar: Las escuelas pueden solicitar documentos que prueben que vives dentro de sus l\u00edmites. Esto puede incluir facturas de servicios, contratos de arrendamiento o declaraciones juradas.  <\/span>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t<li class=\"premium-bullet-list-content elementor-repeater-item-adbbd50\">\n\t\t\t\t<div class=\"premium-bullet-list-text\">\n\t\t\t\t\t\t\t\t<div class=\"premium-bullet-list-text-wrapper\">\n\t\t\t\t\t<span class=\"premium-bullet-text\" data-text=\"-\"> - <\/span>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t<li class=\"premium-bullet-list-content elementor-repeater-item-ce798d6\">\n\t\t\t\t<div class=\"premium-bullet-list-text\">\n\t\t\t\t\t\t\t\t<div class=\"premium-bullet-list-wrapper\">\n\t\t\t\t\t<div class=\"premium-drawable-icon\"><i class=\"premium-svg-nodraw far fa-hand-peace\" aria-hidden=\"true\"><\/i><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"premium-bullet-list-text-wrapper\">\n\t\t\t\t\t<span class=\"premium-bullet-text\" data-text=\" 2. Prueba de edad: Para verificar que tu hijo cumple con los requisitos de edad de la escuela, pueden solicitarte un certificado de nacimiento o registros escolares previos. No pueden negar la inscripci\u00f3n si tu hijo tiene un certificado de nacimiento extranjero o si carece de uno.\">  2. Prueba de edad: Para verificar que tu hijo cumple con los requisitos de edad de la escuela, pueden solicitarte un certificado de nacimiento o registros escolares previos. No pueden negar la inscripci\u00f3n si tu hijo tiene un certificado de nacimiento extranjero o si carece de uno. <\/span>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/li>\n\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8b4bb7 elementor-widget elementor-widget-text-editor\" data-id=\"b8b4bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW3953808 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW3953808 BCX4\">Es importante destacar que<\/span><span class=\"NormalTextRun SCXW3953808 BCX4\">,<\/span><span class=\"NormalTextRun SCXW3953808 BCX4\"> mientras las escuelas pueden <\/span><\/span><a href=\"https:\/\/loigica.com\/es\/articulos-green-card-ssn\/\"><span class=\"TextRun SCXW3953808 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW3953808 BCX4\">solicitar un n\u00famero de Segur<\/span><span class=\"NormalTextRun SCXW3953808 BCX4\">idad<\/span><span class=\"NormalTextRun SCXW3953808 BCX4\"> Social para fines de identificaci\u00f3n<\/span><\/span><\/a><span class=\"TextRun SCXW3953808 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW3953808 BCX4\">, no es obligatorio proporcionarlo. No pueden negar la inscripci\u00f3n a tu hijo si decides no compartir ese n\u00famero. Adem\u00e1s, no pueden preguntarte ni a ti ni a tu hijo sobre su estatus migratorio durante el proceso de inscripci\u00f3n.<\/span><\/span><span class=\"EOP SCXW3953808 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b24850 elementor-widget elementor-widget-text-editor\" data-id=\"1b24850\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW68885619 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW68885619 BCX4\">Este enfoque inclusivo y no discriminatorio en las pol\u00edticas de inscripci\u00f3n escolar asegura que todos los ni\u00f1os, independientemente de su origen o estatus migratorio, tengan acceso a la educaci\u00f3n. Esto no solo cumple con los requisitos <\/span><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW68885619 BCX4\">legales<\/span><span class=\"NormalTextRun SCXW68885619 BCX4\"> sino que tambi\u00e9n promueve una sociedad m\u00e1s integrada y equitativa, <\/span><span class=\"NormalTextRun SCXW68885619 BCX4\">una en la que<\/span><span class=\"NormalTextRun SCXW68885619 BCX4\"> cada ni\u00f1o tiene la oportunidad de alcanzar su m\u00e1ximo potencial.<\/span><\/span><span class=\"EOP SCXW68885619 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6d823f elementor-widget elementor-widget-heading\" data-id=\"f6d823f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> \u00bfCu\u00e1l es el impacto del I-140 en la educaci\u00f3n de tus hijos?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c0a67c elementor-widget elementor-widget-text-editor\" data-id=\"5c0a67c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW220120877 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW220120877 BCX4\">La<\/span><span class=\"NormalTextRun SCXW220120877 BCX4\"> espera por la aprobaci\u00f3n del I-140 no limita el derecho de tus hijos a la educaci\u00f3n. Como hemos visto en la decisi\u00f3n de <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW220120877 BCX4\">Plyler<\/span><span class=\"NormalTextRun SCXW220120877 BCX4\"> v. <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW220120877 BCX4\">Doe<\/span><span class=\"NormalTextRun SCXW220120877 BCX4\">, todos los ni\u00f1os en los Estados Unidos tienen el derecho a recibir educaci\u00f3n p\u00fablica, sin importar el estatus migratorio de sus padres o el suyo propio. Esto significa que mientras tu formulario I-140 est\u00e1 en proceso, tus hijos pueden y deben tener acceso a la educaci\u00f3n p\u00fablica.<\/span><\/span><span class=\"EOP SCXW220120877 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-946e625 elementor-widget elementor-widget-text-editor\" data-id=\"946e625\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">\u00a0<span class=\"TextRun SCXW156097629 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW156097629 BCX4\">La pol\u00edtica educativa en <\/span><span class=\"NormalTextRun SCXW156097629 BCX4\">los Estados Unidos <\/span><span class=\"NormalTextRun SCXW156097629 BCX4\">busca<\/span><span class=\"NormalTextRun SCXW156097629 BCX4\"> garantizar que todos los ni\u00f1os, sin distinci\u00f3n, reciban una educaci\u00f3n que <\/span><span class=\"NormalTextRun SCXW156097629 BCX4\">los<\/span><span class=\"NormalTextRun SCXW156097629 BCX4\"> prepare para ser miembros activos y aportantes de la sociedad. Este enfoque inclusivo se mantiene incluso si tu familia se encuentra en una situaci\u00f3n de incertidumbre migratoria. La educaci\u00f3n es un derecho b\u00e1sico que se extiende a todos los ni\u00f1os, independientemente de la etapa en la que se encuentre la petici\u00f3n I-140 de sus padres.<\/span><\/span><span class=\"EOP SCXW156097629 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a55335 elementor-widget elementor-widget-text-editor\" data-id=\"3a55335\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW72937957 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW72937957 BCX4\">E<\/span><span class=\"NormalTextRun SCXW72937957 BCX4\">sto <\/span><span class=\"NormalTextRun SCXW72937957 BCX4\">significa que puedes inscribir a tus hijos en una escuela p\u00fablica local presentando los documentos requeridos, como prueba de residencia y edad, sin la necesidad de revelar su estatus migratorio o el tuyo. Las escuelas est\u00e1n preparadas para acoger a estudiantes de diversos or\u00edgenes y condiciones, asegurando que tu situaci\u00f3n migratoria no sea un obst\u00e1culo para la educaci\u00f3n de tus hijos.<\/span><\/span><span class=\"EOP SCXW72937957 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74454ce elementor-widget elementor-widget-text-editor\" data-id=\"74454ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"NormalTextRun SCXW50969058 BCX4\">Por tanto, si te encuentras en el proceso de esperar la aprobaci\u00f3n del formulario I-140, puedes estar tranquilo sabiendo que tus hijos tienen el derecho y la oportunidad de continuar su educaci\u00f3n. Esta continuidad es vital para su desarrollo y bienestar<\/span><span class=\"NormalTextRun SCXW50969058 BCX4\">. P<\/span><span class=\"NormalTextRun SCXW50969058 BCX4\">roporciona una base s\u00f3lida durante un per\u00edodo que puede ser desafiante para la familia.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4d3ab elementor-widget elementor-widget-text-editor\" data-id=\"ae4d3ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW19367633 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW19367633 BCX4\">As\u00ed que, recuerda, l<\/span><span class=\"NormalTextRun SCXW19367633 BCX4\">a educaci\u00f3n en <\/span><span class=\"NormalTextRun SCXW19367633 BCX4\">los Estados Unidos<\/span><span class=\"NormalTextRun SCXW19367633 BCX4\"> se fundamenta en el principio de igualdad de oportunidades<\/span><span class=\"NormalTextRun SCXW19367633 BCX4\">. Y esto<\/span><span class=\"NormalTextRun SCXW19367633 BCX4\"> incluye el acceso ininterrumpido a la educaci\u00f3n para los hijos de inmigrantes en proceso de obtener su residencia permanente.<\/span><\/span><span class=\"EOP SCXW19367633 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25a7209 elementor-widget elementor-widget-heading\" data-id=\"25a7209\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Otras preguntas frecuentes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9873de elementor-widget elementor-widget-eael-feature-list\" data-id=\"d9873de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-feature-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"-icon-position-left -tablet-icon-position-left -mobile-icon-position-left\">\n\t\t\t<ul id=\"eael-feature-list-d9873de\" class=\"eael-feature-list-items circle stacked  eael-feature-list-vertical\" data-layout-tablet=\"vertical\" data-layout-mobile=\"vertical\">\n\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-2d80471\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-0\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\"> 1. \u00bfQu\u00e9 pasa si mi empleador a\u00fan no ha presentado el formulario I-140, pero planea hacerlo pronto? \u00bfPueden mis hijos asistir a la escuela mientras tanto?<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">S\u00ed, tus hijos pueden asistir a la escuela incluso si el I-140 a\u00fan no se ha presentado. El derecho a la educaci\u00f3n p\u00fablica no depende de la presentaci\u00f3n de este formulario.<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-4920398\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-1\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\"> 2. \u00bfNecesito revelar mi estatus migratorio o el de mis hijos al inscribirlos en una escuela p\u00fablica? \u00bfQu\u00e9 documentos debo presentar para su inscripci\u00f3n?<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">No es necesario revelar el estatus migratorio para la inscripci\u00f3n escolar. Solo se requieren pruebas de residencia y edad del estudiante.<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-b58ea19\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-2\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\"> 3. \u00bfQu\u00e9 sucede si mi petici\u00f3n I-140 es denegada? \u00bfMis hijos deben dejar la escuela?<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">No, la denegaci\u00f3n de tu I-140 no afecta el derecho de tus hijos a continuar su educaci\u00f3n. Pueden permanecer en la escuela independientemente del resultado de tu proceso migratorio. <\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-1279244\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-3\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">4. \u00bfPueden mis hijos acceder a programas educativos especiales si a\u00fan estamos esperando la aprobaci\u00f3n del I-140?<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">S\u00ed, tus hijos tienen derecho a acceder a todos los programas educativos ofrecidos por las escuelas p\u00fablicas, incluyendo programas especiales, mientras esperas la aprobaci\u00f3n del I-140.<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t                <li class=\"eael-feature-list-item elementor-repeater-item-3e16bab\">\n                    \n\t\t\t\t\t\t<div class=\"eael-feature-list-icon-box\">\n\t\t\t\t\t\t\t<div class=\"eael-feature-list-icon-inner\">\n\n\t\t\t\t\t\t\t\t<span class=\"eael-feature-list-icon fl-icon-4\">\n\n\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"eael-feature-list-content-box\">\n                            <h2 class=\"eael-feature-list-title\">5. \u00bfC\u00f3mo afecta mi estatus de espera del I-140 a la inscripci\u00f3n de mis hijos en actividades extracurriculares en la escuela?<\/h2>\t\t\t\t\t\t<p class=\"eael-feature-list-content\">Tu estatus de espera del I-140 no impide que tus hijos participen en actividades extracurriculares. Las escuelas ofrecen estas actividades a todos los estudiantes, sin considerar su estatus migratorio.<\/p>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b625dc8 elementor-widget elementor-widget-global elementor-global-11490 elementor-widget-image\" data-id=\"b625dc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/share.hsforms.com\/1O6t0DMs-SriQsTw3E9tfZwzfjc\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/contacte-un-abogado-loigica-abogados-inmigracion-colombia-miami-1024x512.jpg\" class=\"elementor-animation-float attachment-large size-large wp-image-10399\" alt=\"P\u00f3ngase en contacto con nuestros abogados haciendo click aqu\u00ed. Este blog no constituye asesoramiento jur\u00eddico.\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/contacte-un-abogado-loigica-abogados-inmigracion-colombia-miami-1024x512.jpg 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/contacte-un-abogado-loigica-abogados-inmigracion-colombia-miami-300x150.jpg 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/contacte-un-abogado-loigica-abogados-inmigracion-colombia-miami-768x384.jpg 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/contacte-un-abogado-loigica-abogados-inmigracion-colombia-miami.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-69ddd8f0\" data-id=\"69ddd8f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6481777f elementor-widget elementor-widget-heading\" data-id=\"6481777f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recomendados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11c88f4b elementor-grid-1 elementor-posts--align-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"11c88f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8877 post type-post status-publish format-standard has-post-thumbnail hentry category-visas-trabajo-talento tag-eb1-a tag-eb2\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/loigica.com\/es\/articulos-visa-eb1-y-visa-eb2\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Diferencia-EB1-y-EB2.jpg\" class=\"attachment-full size-full wp-image-12370\" alt=\"\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Diferencia-EB1-y-EB2.jpg 1920w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Diferencia-EB1-y-EB2-300x169.jpg 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Diferencia-EB1-y-EB2-1024x576.jpg 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Diferencia-EB1-y-EB2-768x432.jpg 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Diferencia-EB1-y-EB2-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/loigica.com\/es\/articulos-visa-eb1-y-visa-eb2\/\" >\n\t\t\t\t\u00bfCu\u00e1l es la diferencia entre la Visa EB-1 y la Visa EB-2?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tMarketing Loigica\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tmayo 12, 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/loigica.com\/es\/articulos-visa-eb1-y-visa-eb2\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre \u00bfCu\u00e1l es la diferencia entre la Visa EB-1 y la Visa EB-2?\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4692 post type-post status-publish format-standard has-post-thumbnail hentry category-residencia-ciudadania category-visas-trabajo-talento tag-eb2-niw tag-eb2-por-interes-nacional\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3.webp\" class=\"attachment-full size-full wp-image-23098\" alt=\"Profesiones para la visa EB2\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3.webp 1920w, https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3-300x169.webp 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3-1024x576.webp 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3-768x432.webp 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3-1536x864.webp 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/\" >\n\t\t\t\t\u00bfQu\u00e9 profesiones califican a la visa EB-2 por inter\u00e9s nacional?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tMarketing Loigica\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tfebrero 17, 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre \u00bfQu\u00e9 profesiones califican a la visa EB-2 por inter\u00e9s nacional?\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2266e67 elementor-widget elementor-widget-text-editor\" data-id=\"2266e67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW221075419 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW221075419 BCX4\">El di\u00e1logo y la colaboraci\u00f3n entre pa\u00edses, as\u00ed como entre organizaciones intergubernamentales y no gubernamentales, son esenciales para desarrollar pol\u00edticas efectivas que respeten los derechos de los migrantes y aprovechen su potencial para contribuir al desarrollo sostenible. El fortalecimiento de los derechos laborales de los trabajadores migrantes, la mejora de los datos sobre migraci\u00f3n para pol\u00edticas basadas en datos emp\u00edricos y el establecimiento de esfuerzos internacionales para los casos de migrantes desaparecidos son solo algunos de los temas que se abordan en estos foros globales.<\/span><\/span><span class=\"EOP SCXW221075419 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9c66ab elementor-widget elementor-widget-text-editor\" data-id=\"b9c66ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW226726692 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW226726692 BCX4\">Si han pasado m\u00e1s de tres semanas (o dos semanas en caso de haber <\/span><span class=\"NormalTextRun SCXW226726692 BCX4\">solicitado el SSN tras haber llegado a los Estados Unidos)<\/span><span class=\"NormalTextRun SCXW226726692 BCX4\"> y no has recibido tu tarjeta de SSN, es momento de actuar. Contacta a la oficina del Seguro Social m\u00e1s cercana. Lleva contigo toda la <\/span><span class=\"NormalTextRun SCXW226726692 BCX4\">documentaci\u00f3n relevante, incluyendo tu pasaporte y tu Green Card. La comunicaci\u00f3n temprana puede resolver r\u00e1pidamente este inconveniente.<\/span><\/span><span class=\"EOP SCXW226726692 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:284,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07edcb9 elementor-widget elementor-widget-text-editor\" data-id=\"07edcb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"TextRun SCXW226726692 BCX4\" lang=\"ES-419\" xml:lang=\"ES-419\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW226726692 BCX4\">Si han pasado m\u00e1s de tres semanas (o dos semanas en caso de haber <\/span><span class=\"NormalTextRun SCXW226726692 BCX4\">solicitado el SSN tras haber llegado a los Estados Unidos)<\/span><span class=\"NormalTextRun SCXW226726692 BCX4\"> y no has recibido tu tarjeta de SSN, es momento de actuar. Contacta a la oficina del Seguro Social m\u00e1s cercana. Lleva contigo toda la <\/span><span class=\"NormalTextRun SCXW226726692 BCX4\">documentaci\u00f3n relevante, incluyendo tu pasaporte y tu Green Card. La comunicaci\u00f3n temprana puede resolver r\u00e1pidamente este inconveniente.<\/span><\/span><span class=\"EOP SCXW226726692 BCX4\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:284,&quot;335559739&quot;:200,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>I-140\u00a0 &#8211; 9 \u00a0minutos de lectura\u00a0 &nbsp; En pocas palabras\u2026 La decisi\u00f3n de Plyler v. Doe de 1982 asegura que todos los ni\u00f1os, independientemente de<\/p>\n","protected":false},"author":5,"featured_media":11913,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[101,100],"tags":[59,56],"class_list":["post-11910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmigracion-familiar","category-visas-trabajo-talento","tag-eb3","tag-perm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPueden mis hijos estudiar mientras aprueban I-140? | LOIGICA Abogados de Inmigraci\u00f3n<\/title>\n<meta name=\"description\" content=\"El formulario I-140 es tu llave hacia un futuro estable en Estados Unidos como trabajador inmigrante buscando residencia permanente. \u00a1Conoce m\u00e1s detalles!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPueden mis hijos estudiar mientras aprueban I-140? | LOIGICA Abogados de Inmigraci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El formulario I-140 es tu llave hacia un futuro estable en Estados Unidos como trabajador inmigrante buscando residencia permanente. \u00a1Conoce m\u00e1s detalles!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/\" \/>\n<meta property=\"og:site_name\" content=\"Loigica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loigica\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-16T12:06:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T16:14:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/I-140-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camilo Espinosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Loigica\" \/>\n<meta name=\"twitter:site\" content=\"@Loigica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camilo Espinosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/\"},\"author\":{\"name\":\"Camilo Espinosa\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/person\\\/7513b47226d48ec32034cb6e37c585c3\"},\"headline\":\"\u00bfPueden mis hijos estudiar mientras aprueban mi I-140?\",\"datePublished\":\"2024-02-16T12:06:25+00:00\",\"dateModified\":\"2026-01-27T16:14:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/\"},\"wordCount\":1801,\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/I-140-.jpg\",\"keywords\":[\"EB3\",\"PERM\"],\"articleSection\":[\"Inmigraci\u00f3n Familiar\",\"Visas de Trabajo y Talento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/\",\"name\":\"\u00bfPueden mis hijos estudiar mientras aprueban I-140? | LOIGICA Abogados de Inmigraci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/I-140-.jpg\",\"datePublished\":\"2024-02-16T12:06:25+00:00\",\"dateModified\":\"2026-01-27T16:14:56+00:00\",\"description\":\"El formulario I-140 es tu llave hacia un futuro estable en Estados Unidos como trabajador inmigrante buscando residencia permanente. \u00a1Conoce m\u00e1s detalles!\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-formulario-i-40-hijos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/I-140-.jpg\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/I-140-.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"name\":\"Loigica\",\"description\":\"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM\",\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loigica.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\",\"name\":\"Loigica\",\"alternateName\":\"Loigica Immigration Attorneys\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"width\":369,\"height\":317,\"caption\":\"Loigica\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loigica\\\/\",\"https:\\\/\\\/x.com\\\/Loigica\",\"https:\\\/\\\/www.instagram.com\\\/loigica\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Loigica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/person\\\/7513b47226d48ec32034cb6e37c585c3\",\"name\":\"Camilo Espinosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g\",\"caption\":\"Camilo Espinosa\"},\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/author\\\/camilo-espinosa-esq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPueden mis hijos estudiar mientras aprueban I-140? | LOIGICA Abogados de Inmigraci\u00f3n","description":"El formulario I-140 es tu llave hacia un futuro estable en Estados Unidos como trabajador inmigrante buscando residencia permanente. \u00a1Conoce m\u00e1s detalles!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPueden mis hijos estudiar mientras aprueban I-140? | LOIGICA Abogados de Inmigraci\u00f3n","og_description":"El formulario I-140 es tu llave hacia un futuro estable en Estados Unidos como trabajador inmigrante buscando residencia permanente. \u00a1Conoce m\u00e1s detalles!","og_url":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/","og_site_name":"Loigica","article_publisher":"https:\/\/www.facebook.com\/loigica\/","article_published_time":"2024-02-16T12:06:25+00:00","article_modified_time":"2026-01-27T16:14:56+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/I-140-.jpg","type":"image\/jpeg"}],"author":"Camilo Espinosa","twitter_card":"summary_large_image","twitter_creator":"@Loigica","twitter_site":"@Loigica","twitter_misc":{"Escrito por":"Camilo Espinosa","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/#article","isPartOf":{"@id":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/"},"author":{"name":"Camilo Espinosa","@id":"https:\/\/loigica.com\/es\/#\/schema\/person\/7513b47226d48ec32034cb6e37c585c3"},"headline":"\u00bfPueden mis hijos estudiar mientras aprueban mi I-140?","datePublished":"2024-02-16T12:06:25+00:00","dateModified":"2026-01-27T16:14:56+00:00","mainEntityOfPage":{"@id":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/"},"wordCount":1801,"publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"image":{"@id":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/I-140-.jpg","keywords":["EB3","PERM"],"articleSection":["Inmigraci\u00f3n Familiar","Visas de Trabajo y Talento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/","url":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/","name":"\u00bfPueden mis hijos estudiar mientras aprueban I-140? | LOIGICA Abogados de Inmigraci\u00f3n","isPartOf":{"@id":"https:\/\/loigica.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/#primaryimage"},"image":{"@id":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/I-140-.jpg","datePublished":"2024-02-16T12:06:25+00:00","dateModified":"2026-01-27T16:14:56+00:00","description":"El formulario I-140 es tu llave hacia un futuro estable en Estados Unidos como trabajador inmigrante buscando residencia permanente. \u00a1Conoce m\u00e1s detalles!","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/articulos-formulario-i-40-hijos\/#primaryimage","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/I-140-.jpg","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/I-140-.jpg","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/loigica.com\/es\/#website","url":"https:\/\/loigica.com\/es\/","name":"Loigica","description":"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM","publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loigica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loigica.com\/es\/#organization","name":"Loigica","alternateName":"Loigica Immigration Attorneys","url":"https:\/\/loigica.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","width":369,"height":317,"caption":"Loigica"},"image":{"@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loigica\/","https:\/\/x.com\/Loigica","https:\/\/www.instagram.com\/loigica\/","https:\/\/www.youtube.com\/@Loigica\/"]},{"@type":"Person","@id":"https:\/\/loigica.com\/es\/#\/schema\/person\/7513b47226d48ec32034cb6e37c585c3","name":"Camilo Espinosa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g","caption":"Camilo Espinosa"},"url":"https:\/\/loigica.com\/es\/author\/camilo-espinosa-esq\/"}]}},"_links":{"self":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/11910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/comments?post=11910"}],"version-history":[{"count":16,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/11910\/revisions"}],"predecessor-version":[{"id":11931,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/11910\/revisions\/11931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media\/11913"}],"wp:attachment":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media?parent=11910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/categories?post=11910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/tags?post=11910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}