{"id":4692,"date":"2023-02-17T17:16:49","date_gmt":"2023-02-17T22:16:49","guid":{"rendered":"https:\/\/loigica.com\/?p=4692"},"modified":"2026-03-25T09:23:16","modified_gmt":"2026-03-25T13:23:16","slug":"artculos-visa-eb2-profesiones","status":"publish","type":"post","link":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/","title":{"rendered":"\u00bfQu\u00e9 profesiones califican a la visa EB-2 por inter\u00e9s nacional?"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4692\" class=\"elementor elementor-4692\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5acdfaf e-flex e-con-boxed e-con e-parent\" data-id=\"5acdfaf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-946c388 elementor-widget elementor-widget-text-editor\" data-id=\"946c388\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1380\" data-end=\"1525\">Cuando muchas personas buscan informaci\u00f3n sobre la <strong data-start=\"1431\" data-end=\"1443\">visa EB2<\/strong>, suelen hacer la misma pregunta: <strong data-start=\"1477\" data-end=\"1525\">\u00bfqu\u00e9 profesiones califican para la visa EB2?<\/strong><\/p><p data-start=\"1380\" data-end=\"1525\">\u00a0<\/p><p data-start=\"1527\" data-end=\"2108\">La respuesta corta es esta: <strong data-start=\"1555\" data-end=\"1628\">no existe una lista oficial de profesiones aprobadas para el EB-2 NIW<\/strong>. En realidad, USCIS primero analiza si la persona califica para la categor\u00eda base EB-2 como profesional con t\u00edtulo avanzado o como persona con habilidad excepcional. Despu\u00e9s, en los casos de <strong data-start=\"1820\" data-end=\"1854\">National Interest Waiver (NIW)<\/strong>, revisa si el proyecto profesional propuesto tiene m\u00e9rito sustancial e importancia nacional, si el solicitante est\u00e1 bien posicionado para impulsarlo y si conviene eximir la oferta laboral y la certificaci\u00f3n laboral.<\/p><p data-start=\"1527\" data-end=\"2108\">\u00a0<\/p><p data-start=\"2110\" data-end=\"2260\">Por eso, m\u00e1s que pensar en \u201cprofesiones aprobadas\u201d, conviene pensar en <strong data-start=\"2181\" data-end=\"2259\">perfiles profesionales que suelen adaptarse bien a una estrategia EB-2 NIW<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-422e640 elementor-widget elementor-widget-video\" data-id=\"422e640\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=S07oLdyBeng&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5478bc e-flex e-con-boxed e-con e-parent\" data-id=\"d5478bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c58de6d elementor-widget elementor-widget-text-editor\" data-id=\"c58de6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-section-id=\"1gomnzq\" data-start=\"2262\" data-end=\"2291\"><strong>Qu\u00e9 exige la visa EB-2 NIW<\/strong><\/h2><p data-start=\"2293\" data-end=\"2614\">La categor\u00eda <strong data-start=\"2306\" data-end=\"2314\">EB-2<\/strong> aplica, en t\u00e9rminos generales, a dos grupos: profesionales con <strong data-start=\"2378\" data-end=\"2397\">advanced degree <\/strong>(t\u00edtulo avanzado)\u00a0y personas con <strong data-start=\"2413\" data-end=\"2436\">exceptional ability <\/strong>(habilidad excepcional). Sobre esa base, el NIW permite pedir una exenci\u00f3n del requisito de oferta laboral y certificaci\u00f3n laboral si se cumplen ciertos criterios.<\/p><p data-start=\"2293\" data-end=\"2614\">\u00a0<\/p><p data-start=\"2616\" data-end=\"2731\">Esto significa que una profesi\u00f3n, por s\u00ed sola, no determina la elegibilidad. Lo que realmente importa es demostrar:<\/p><p data-start=\"2616\" data-end=\"2731\">\u00a0<\/p><ul data-start=\"2733\" data-end=\"2924\"><li data-section-id=\"p87m49\" data-start=\"2733\" data-end=\"2785\">que el perfil encaja dentro de la base legal EB-2;<\/li><li data-section-id=\"1kigjd\" data-start=\"2786\" data-end=\"2845\">que la actividad o proyecto propuesto tiene impacto real;<\/li><li data-section-id=\"1cclzbu\" data-start=\"2846\" data-end=\"2924\">que existe evidencia s\u00f3lida de trayectoria, logros y capacidad de ejecuci\u00f3n.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f761aeb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f761aeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-316f8f7 e-flex e-con-boxed e-con e-parent\" data-id=\"316f8f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-731d2ac elementor-widget elementor-widget-text-editor\" data-id=\"731d2ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-section-id=\"u2xxae\" data-start=\"2926\" data-end=\"2986\"><strong>Profesiones para la visa EB2 que suelen tener buen encaje<\/strong><\/h2><p data-start=\"2988\" data-end=\"3109\">Aunque no existe una lista cerrada, hay perfiles que suelen aparecer con frecuencia en casos <span style=\"color: #0a1e36;\"><a style=\"color: #0a1e36;\" href=\"https:\/\/loigica.com\/es\/inmigracion\/visas-talento\/visa-eb-2-niw\/\" target=\"_blank\" rel=\"noopener\">EB-2 NIW<\/a><\/span> bien estructurados.<\/p><h3 data-section-id=\"5swmp\" data-start=\"3111\" data-end=\"3156\"><strong>M\u00e9dicos y otros profesionales de la salud<\/strong><\/h3><p data-start=\"3158\" data-end=\"3626\">Los m\u00e9dicos, investigadores cl\u00ednicos, especialistas en salud p\u00fablica y otros profesionales sanitarios suelen tener perfiles s\u00f3lidos para este tipo de estrategia, especialmente cuando su trabajo se relaciona con atenci\u00f3n m\u00e9dica, investigaci\u00f3n, prevenci\u00f3n, acceso a salud o pol\u00edticas p\u00fablicas. <span style=\"color: #0a1e36;\"><a style=\"color: #0a1e36;\" href=\"https:\/\/www.uscis.gov\/es\" target=\"_blank\" rel=\"noopener\"><strong>USCIS<\/strong><\/a><\/span> incluso tiene una v\u00eda espec\u00edfica de <strong data-start=\"3492\" data-end=\"3530\">Physician National Interest Waiver<\/strong> para ciertos m\u00e9dicos que cumplen requisitos particulares.<\/p><p data-start=\"3158\" data-end=\"3626\">\u00a0<\/p><h3 data-section-id=\"1vhwa3z\" data-start=\"3628\" data-end=\"3642\"><strong>Ingenieros<\/strong><\/h3><p data-start=\"3644\" data-end=\"3741\">Los ingenieros tambi\u00e9n suelen tener un buen encaje en casos EB-2 NIW. Esto incluye perfiles como:<\/p><p data-start=\"3644\" data-end=\"3741\">\u00a0<\/p><ul data-start=\"3743\" data-end=\"3882\"><li data-section-id=\"1ylep3t\" data-start=\"3743\" data-end=\"3768\">ingenieros ambientales;<\/li><li data-section-id=\"1hywb1k\" data-start=\"3769\" data-end=\"3792\">ingenieros mec\u00e1nicos;<\/li><li data-section-id=\"snwb7v\" data-start=\"3793\" data-end=\"3819\">ingenieros industriales;<\/li><li data-section-id=\"fihe4d\" data-start=\"3820\" data-end=\"3845\">ingenieros de petr\u00f3leo;<\/li><li data-section-id=\"vrrc4p\" data-start=\"3846\" data-end=\"3882\">ingenieros de software o sistemas.<\/li><\/ul><p>\u00a0<\/p><p data-start=\"3884\" data-end=\"4280\">En estos casos, la clave no suele ser el t\u00edtulo de ingeniero en s\u00ed mismo, sino <strong data-start=\"3963\" data-end=\"4034\">c\u00f3mo la especialidad aporta a sectores relevantes en Estados Unidos<\/strong>, como energ\u00eda, infraestructura, manufactura, transporte, automatizaci\u00f3n o sostenibilidad. USCIS reconoce que el an\u00e1lisis debe enfocarse en el endeavor propuesto y su impacto, no solo en el cargo profesional.<\/p><p data-start=\"3884\" data-end=\"4280\">\u00a0<\/p><h3 data-section-id=\"14t8yw7\" data-start=\"4282\" data-end=\"4304\"><strong>Profesionales STEM<\/strong><\/h3><p data-start=\"4306\" data-end=\"4657\">Los perfiles STEM suelen tener mucha relevancia en este tipo de peticiones. Esto incluye cient\u00edficos, tecn\u00f3logos, matem\u00e1ticos e investigadores en distintas ramas. USCIS actualiz\u00f3 su gu\u00eda para explicar con m\u00e1s detalle c\u00f3mo eval\u00faa peticiones NIW, incluidas aquellas relacionadas con \u00e1reas t\u00e9cnicas y especializadas.<\/p><p data-start=\"4306\" data-end=\"4657\">\u00a0<\/p><p data-start=\"4659\" data-end=\"4936\">Sin embargo, incluso en profesiones STEM, no alcanza con trabajar en un \u00e1rea \u201cimportante\u201d. Tambi\u00e9n hay que probar por qu\u00e9 el proyecto concreto aporta valor a nivel nacional y por qu\u00e9 el solicitante est\u00e1 bien posicionado para desarrollarlo.<\/p><p data-start=\"4659\" data-end=\"4936\">\u00a0<\/p><h3 data-section-id=\"16l3anh\" data-start=\"4938\" data-end=\"4995\"><strong>Profesores, investigadores y profesionales acad\u00e9micos<\/strong><\/h3><p data-start=\"4997\" data-end=\"5286\">Los profesores universitarios, investigadores, acad\u00e9micos y especialistas en desarrollo de conocimiento tambi\u00e9n pueden encajar bien en EB-2 NIW, sobre todo cuando su trabajo se conecta con innovaci\u00f3n, educaci\u00f3n avanzada, transferencia de conocimiento o desarrollo de sectores estrat\u00e9gicos.<\/p><p data-start=\"4997\" data-end=\"5286\">\u00a0<\/p><p data-start=\"5288\" data-end=\"5445\">En estos casos, la evidencia suele apoyarse en publicaciones, experiencia docente, participaci\u00f3n en proyectos, liderazgo acad\u00e9mico o contribuciones t\u00e9cnicas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdd1ca3 elementor-widget elementor-widget-image\" data-id=\"fdd1ca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/37-4-1024x576.webp\" class=\"attachment-large size-large wp-image-23099\" alt=\"Visa EB-2 NIW\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/37-4-1024x576.webp 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/37-4-300x169.webp 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/37-4-768x432.webp 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/37-4-1536x864.webp 1536w, https:\/\/loigica.com\/es\/wp-content\/uploads\/37-4.webp 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3909136 e-flex e-con-boxed e-con e-parent\" data-id=\"3909136\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0731a3 elementor-widget elementor-widget-text-editor\" data-id=\"e0731a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-section-id=\"gix2sn\" data-start=\"5447\" data-end=\"5494\"><strong>Empresarios, inversionistas y emprendedores<\/strong><\/h3><p data-start=\"5496\" data-end=\"5967\">Los empresarios y emprendedores pueden construir casos s\u00f3lidos de EB-2 NIW cuando logran demostrar que su actividad propuesta generar\u00e1 beneficios amplios, como creaci\u00f3n de empleo, innovaci\u00f3n, impacto econ\u00f3mico o soluciones en sectores relevantes. USCIS incluye a los emprendedores dentro de sus posibles v\u00edas de inmigraci\u00f3n basada en empleo, incluido el EB-2 NIW, siempre que cumplan con la base legal y con los criterios del waiver.<\/p><p data-start=\"5496\" data-end=\"5967\">\u00a0<\/p><p data-start=\"5969\" data-end=\"6129\">En estos perfiles, el an\u00e1lisis suele concentrarse mucho en el <strong data-start=\"6031\" data-end=\"6052\">modelo de negocio<\/strong>, la capacidad real de ejecuci\u00f3n y el impacto del proyecto en Estados Unidos.<\/p><p data-start=\"5969\" data-end=\"6129\">\u00a0<\/p><h3 data-section-id=\"1rb8voi\" data-start=\"6131\" data-end=\"6146\"><strong>Arquitectos<\/strong><\/h3><p data-start=\"6148\" data-end=\"6517\">Los arquitectos tambi\u00e9n pueden tener casos viables, especialmente cuando su trayectoria o proyecto se conecta con investigaci\u00f3n, planificaci\u00f3n, sostenibilidad, infraestructura o innovaci\u00f3n aplicada. Aun as\u00ed, si el objetivo es ejercer arquitectura en una jurisdicci\u00f3n espec\u00edfica, pueden existir requisitos estatales o de licenciamiento separados del an\u00e1lisis migratorio.<\/p><p data-start=\"6148\" data-end=\"6517\">\u00a0<\/p><h3 data-section-id=\"15cf456\" data-start=\"6519\" data-end=\"6569\"><strong>Contadores, consultores y perfiles de negocios<\/strong><\/h3><p data-start=\"6571\" data-end=\"6914\">Los contadores, analistas financieros, consultores y otros profesionales de negocios pueden calificar en algunos casos, pero normalmente necesitan una estrategia argumentativa m\u00e1s trabajada. El punto central suele ser demostrar que su conocimiento produce un beneficio relevante para una industria, regi\u00f3n o sector econ\u00f3mico en Estados Unidos.<\/p><p data-start=\"6571\" data-end=\"6914\">\u00a0<\/p><h3 data-section-id=\"dce5br\" data-start=\"6916\" data-end=\"6954\"><strong>Profesionales en ciencias sociales<\/strong><\/h3><p data-start=\"6956\" data-end=\"7295\">Economistas, soci\u00f3logos, especialistas en pol\u00edticas p\u00fablicas, historiadores, antrop\u00f3logos y otros profesionales de ciencias sociales tambi\u00e9n pueden tener casos viables si su trabajo aporta a problemas concretos de relevancia nacional. En estos perfiles, la narrativa del caso y la evidencia de impacto suelen ser especialmente importantes.<\/p><h3 data-section-id=\"1as4qhr\" data-start=\"7297\" data-end=\"7345\">\u00a0<\/h3><h3 data-section-id=\"1as4qhr\" data-start=\"7297\" data-end=\"7345\"><strong>Artistas, m\u00fasicos y otros perfiles creativos<\/strong><\/h3><p data-start=\"7347\" data-end=\"7820\">Los artistas, m\u00fasicos y otros perfiles creativos no quedan autom\u00e1ticamente excluidos del EB-2 NIW. Sin embargo, en muchos casos tambi\u00e9n conviene evaluar si una categor\u00eda como <strong data-start=\"7522\" data-end=\"7530\">EB-1<\/strong> u otra v\u00eda migratoria encaja mejor seg\u00fan el nivel de reconocimiento, el tipo de trayectoria y la evidencia disponible. La clave sigue siendo la misma: no basta con el talento; hay que demostrar impacto, posicionamiento y m\u00e9rito del endeavor propuesto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54010ea elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"54010ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3371eca e-flex e-con-boxed e-con e-parent\" data-id=\"3371eca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3bb3ab elementor-widget elementor-widget-text-editor\" data-id=\"b3bb3ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-section-id=\"1f1caxp\" data-start=\"7822\" data-end=\"7870\"><strong>Lo que realmente hace fuerte un caso EB-2 NIW<\/strong><\/h2><p data-start=\"7872\" data-end=\"8010\">Si alguien busca \u201cprofesiones para la visa EB2\u201d, la pregunta de fondo suele ser otra: <strong data-start=\"7958\" data-end=\"8010\">\u00bfmi perfil se puede convertir en un caso s\u00f3lido?<\/strong><\/p><p data-start=\"7872\" data-end=\"8010\">\u00a0<\/p><p data-start=\"8012\" data-end=\"8053\">Ah\u00ed es donde importa mirar factores como:<\/p><p data-start=\"8012\" data-end=\"8053\">\u00a0<\/p><ul data-start=\"8055\" data-end=\"8285\"><li data-section-id=\"kwhn9p\" data-start=\"8055\" data-end=\"8073\">nivel acad\u00e9mico;<\/li><li data-section-id=\"27vhp4\" data-start=\"8074\" data-end=\"8100\">experiencia profesional;<\/li><li data-section-id=\"joavk4\" data-start=\"8101\" data-end=\"8119\">logros medibles;<\/li><li data-section-id=\"10clsqo\" data-start=\"8120\" data-end=\"8165\">publicaciones, proyectos o reconocimientos;<\/li><li data-section-id=\"1m0vj9d\" data-start=\"8166\" data-end=\"8195\">rol actual en la industria;<\/li><li data-section-id=\"16puunr\" data-start=\"8196\" data-end=\"8252\">claridad del proyecto a desarrollar en Estados Unidos;<\/li><li data-section-id=\"1hvqaal\" data-start=\"8253\" data-end=\"8285\">evidencia de impacto nacional.<\/li><\/ul><p>\u00a0<\/p><p data-start=\"8287\" data-end=\"8566\">En otras palabras, el caso no depende solo de la profesi\u00f3n. Depende de c\u00f3mo se construye la relaci\u00f3n entre el perfil del solicitante y el inter\u00e9s nacional de su trabajo. USCIS deja claro que el an\u00e1lisis del NIW es individual y caso por caso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8864bd elementor-widget elementor-widget-image\" data-id=\"c8864bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/38-2-1024x576.webp\" class=\"attachment-large size-large wp-image-23100\" alt=\"Profesiones para la visa EB2\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/38-2-1024x576.webp 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/38-2-300x169.webp 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/38-2-768x432.webp 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/38-2-1536x864.webp 1536w, https:\/\/loigica.com\/es\/wp-content\/uploads\/38-2.webp 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e5c2eb e-flex e-con-boxed e-con e-parent\" data-id=\"9e5c2eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02854ca elementor-widget elementor-widget-text-editor\" data-id=\"02854ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-section-id=\"m8egt8\" data-start=\"8568\" data-end=\"8625\"><strong>Entonces, \u00bfhay profesiones elegibles para la visa EB2?<\/strong><\/h2><p data-start=\"8627\" data-end=\"8635\">S\u00ed y no. S\u00ed, en el sentido de que <strong data-start=\"8662\" data-end=\"8710\">muchos perfiles profesionales pueden encajar<\/strong> en una estrategia EB-2 NIW. No, en el sentido de que <strong data-start=\"8764\" data-end=\"8827\">USCIS no publica una lista cerrada de profesiones aprobadas<\/strong>. Lo determinante no es el nombre de la carrera, sino la combinaci\u00f3n entre requisitos EB-2, evidencia y proposed endeavor.<\/p><p data-start=\"8627\" data-end=\"8635\">\u00a0<\/p><p data-start=\"8991\" data-end=\"9189\">Por eso, dos personas con la misma profesi\u00f3n pueden tener resultados muy distintos. Una puede tener un caso fuerte, y la otra no, dependiendo de la calidad de la evidencia y del planteo estrat\u00e9gico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a80b192 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a80b192\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5927c0d e-flex e-con-boxed e-con e-parent\" data-id=\"5927c0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f28e9ef elementor-widget elementor-widget-text-editor\" data-id=\"f28e9ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-section-id=\"1q3u061\" data-start=\"9272\" data-end=\"9297\"><strong>C\u00f3mo Loigica puede ayudarte<\/strong><\/h2><p data-start=\"9299\" data-end=\"9476\">En <span style=\"color: #0a1e36;\"><a style=\"color: #0a1e36;\" href=\"https:\/\/loigica.com\/es\/\" target=\"_blank\" rel=\"noopener\"><strong data-start=\"9302\" data-end=\"9313\">Loigica<\/strong><\/a><\/span> ayudamos a profesionales, investigadores, emprendedores y perfiles internacionales a evaluar si realmente tienen una base s\u00f3lida para una estrategia <strong data-start=\"9463\" data-end=\"9475\">EB-2 NIW<\/strong>.<\/p><p data-start=\"9299\" data-end=\"9476\">\u00a0<\/p><p data-start=\"9478\" data-end=\"9674\">Nuestro trabajo no se limita a revisar una profesi\u00f3n. Analizamos el perfil completo, la evidencia disponible, el proposed endeavor y la forma de estructurar un caso migratorio t\u00e9cnicamente s\u00f3lido.<\/p><p data-start=\"9478\" data-end=\"9674\">\u00a0<\/p><p data-start=\"9676\" data-end=\"9699\"><span style=\"color: #0a1e36;\"><a style=\"color: #0a1e36;\" href=\"https:\/\/loigica.com\/es\/contactar\/\" target=\"_blank\" rel=\"noopener\"><strong data-start=\"9676\" data-end=\"9699\">Agenda una consulta<\/strong><\/a><\/span> y comienza tu viaje hacia los Estados Unidos con abogados expertos que te acompa\u00f1ar\u00e1n en cada paso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bbb3693 e-flex e-con-boxed e-con e-parent\" data-id=\"bbb3693\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e775f8 elementor-widget elementor-widget-image\" data-id=\"7e775f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/loigica.com\/es\/contactar\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"296\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/CTA-Template-8-1024x379.webp\" class=\"attachment-large size-large wp-image-23101\" alt=\"Profesiones para la visa EB2\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/CTA-Template-8-1024x379.webp 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/CTA-Template-8-300x111.webp 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/CTA-Template-8-768x284.webp 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/CTA-Template-8.webp 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conoce qu\u00e9 profesiones pueden encajar en una visa EB2 NIW y por qu\u00e9 la elegibilidad depende del perfil, la evidencia y el inter\u00e9s nacional.<\/p>\n","protected":false},"author":10,"featured_media":23098,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[99,100],"tags":[32,40],"class_list":["post-4692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-residencia-ciudadania","category-visas-trabajo-talento","tag-eb2-niw","tag-eb2-por-interes-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profesiones para la visa EB2 | LOIGICA Abogados de Inmigraci\u00f3n<\/title>\n<meta name=\"description\" content=\"La EB2 por inter\u00e9s nacional (NIW) es un tipo de visa de trabajo por la que profesionales altamente calificados inmigran a los Estados Unidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profesiones para la visa EB2 | LOIGICA Abogados de Inmigraci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La EB2 por inter\u00e9s nacional (NIW) es un tipo de visa de trabajo por la que profesionales altamente calificados inmigran a los Estados Unidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/\" \/>\n<meta property=\"og:site_name\" content=\"Loigica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loigica\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-17T22:16:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T13:23:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Marketing Loigica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Loigica\" \/>\n<meta name=\"twitter:site\" content=\"@Loigica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing Loigica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/\"},\"author\":{\"name\":\"Marketing Loigica\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/person\\\/6a15d41086cad2a37fc303253928891d\"},\"headline\":\"\u00bfQu\u00e9 profesiones califican a la visa EB-2 por inter\u00e9s nacional?\",\"datePublished\":\"2023-02-17T22:16:49+00:00\",\"dateModified\":\"2026-03-25T13:23:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/\"},\"wordCount\":1265,\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/36-3.webp\",\"keywords\":[\"EB2 NIW\",\"EB2 por inter\u00e9s nacional\"],\"articleSection\":[\"Residencia y Ciudadan\u00eda\",\"Visas de Trabajo y Talento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/\",\"name\":\"Profesiones para la visa EB2 | LOIGICA Abogados de Inmigraci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/36-3.webp\",\"datePublished\":\"2023-02-17T22:16:49+00:00\",\"dateModified\":\"2026-03-25T13:23:16+00:00\",\"description\":\"La EB2 por inter\u00e9s nacional (NIW) es un tipo de visa de trabajo por la que profesionales altamente calificados inmigran a los Estados Unidos.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/artculos-visa-eb2-profesiones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/36-3.webp\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/36-3.webp\",\"width\":1920,\"height\":1080,\"caption\":\"Profesiones para la visa EB2\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"name\":\"Loigica\",\"description\":\"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM\",\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loigica.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\",\"name\":\"Loigica\",\"alternateName\":\"Loigica Immigration Attorneys\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"width\":369,\"height\":317,\"caption\":\"Loigica\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loigica\\\/\",\"https:\\\/\\\/x.com\\\/Loigica\",\"https:\\\/\\\/www.instagram.com\\\/loigica\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Loigica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/person\\\/6a15d41086cad2a37fc303253928891d\",\"name\":\"Marketing Loigica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/827510faa17dd8e033b5f3ef6464bd354ed87ab2a6f2de7c97673bdd025ee2da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/827510faa17dd8e033b5f3ef6464bd354ed87ab2a6f2de7c97673bdd025ee2da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/827510faa17dd8e033b5f3ef6464bd354ed87ab2a6f2de7c97673bdd025ee2da?s=96&d=mm&r=g\",\"caption\":\"Marketing Loigica\"},\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/author\\\/marketing-loigica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profesiones para la visa EB2 | LOIGICA Abogados de Inmigraci\u00f3n","description":"La EB2 por inter\u00e9s nacional (NIW) es un tipo de visa de trabajo por la que profesionales altamente calificados inmigran a los Estados Unidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/","og_locale":"es_ES","og_type":"article","og_title":"Profesiones para la visa EB2 | LOIGICA Abogados de Inmigraci\u00f3n","og_description":"La EB2 por inter\u00e9s nacional (NIW) es un tipo de visa de trabajo por la que profesionales altamente calificados inmigran a los Estados Unidos.","og_url":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/","og_site_name":"Loigica","article_publisher":"https:\/\/www.facebook.com\/loigica\/","article_published_time":"2023-02-17T22:16:49+00:00","article_modified_time":"2026-03-25T13:23:16+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3.webp","type":"image\/webp"}],"author":"Marketing Loigica","twitter_card":"summary_large_image","twitter_creator":"@Loigica","twitter_site":"@Loigica","twitter_misc":{"Escrito por":"Marketing Loigica","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/#article","isPartOf":{"@id":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/"},"author":{"name":"Marketing Loigica","@id":"https:\/\/loigica.com\/es\/#\/schema\/person\/6a15d41086cad2a37fc303253928891d"},"headline":"\u00bfQu\u00e9 profesiones califican a la visa EB-2 por inter\u00e9s nacional?","datePublished":"2023-02-17T22:16:49+00:00","dateModified":"2026-03-25T13:23:16+00:00","mainEntityOfPage":{"@id":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/"},"wordCount":1265,"publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"image":{"@id":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3.webp","keywords":["EB2 NIW","EB2 por inter\u00e9s nacional"],"articleSection":["Residencia y Ciudadan\u00eda","Visas de Trabajo y Talento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/","url":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/","name":"Profesiones para la visa EB2 | LOIGICA Abogados de Inmigraci\u00f3n","isPartOf":{"@id":"https:\/\/loigica.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/#primaryimage"},"image":{"@id":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3.webp","datePublished":"2023-02-17T22:16:49+00:00","dateModified":"2026-03-25T13:23:16+00:00","description":"La EB2 por inter\u00e9s nacional (NIW) es un tipo de visa de trabajo por la que profesionales altamente calificados inmigran a los Estados Unidos.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/artculos-visa-eb2-profesiones\/#primaryimage","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3.webp","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/36-3.webp","width":1920,"height":1080,"caption":"Profesiones para la visa EB2"},{"@type":"WebSite","@id":"https:\/\/loigica.com\/es\/#website","url":"https:\/\/loigica.com\/es\/","name":"Loigica","description":"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM","publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loigica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loigica.com\/es\/#organization","name":"Loigica","alternateName":"Loigica Immigration Attorneys","url":"https:\/\/loigica.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","width":369,"height":317,"caption":"Loigica"},"image":{"@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loigica\/","https:\/\/x.com\/Loigica","https:\/\/www.instagram.com\/loigica\/","https:\/\/www.youtube.com\/@Loigica\/"]},{"@type":"Person","@id":"https:\/\/loigica.com\/es\/#\/schema\/person\/6a15d41086cad2a37fc303253928891d","name":"Marketing Loigica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/827510faa17dd8e033b5f3ef6464bd354ed87ab2a6f2de7c97673bdd025ee2da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/827510faa17dd8e033b5f3ef6464bd354ed87ab2a6f2de7c97673bdd025ee2da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/827510faa17dd8e033b5f3ef6464bd354ed87ab2a6f2de7c97673bdd025ee2da?s=96&d=mm&r=g","caption":"Marketing Loigica"},"url":"https:\/\/loigica.com\/es\/author\/marketing-loigica\/"}]}},"_links":{"self":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/4692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/comments?post=4692"}],"version-history":[{"count":46,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/4692\/revisions"}],"predecessor-version":[{"id":23104,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/4692\/revisions\/23104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media\/23098"}],"wp:attachment":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media?parent=4692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/categories?post=4692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/tags?post=4692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}