{"id":8891,"date":"2023-04-07T10:21:29","date_gmt":"2023-04-07T14:21:29","guid":{"rendered":"https:\/\/loigica.com\/es\/?p=8891"},"modified":"2026-01-27T11:27:52","modified_gmt":"2026-01-27T16:27:52","slug":"articulos-visa-h1b","status":"publish","type":"post","link":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/","title":{"rendered":"\u00bfPueden los dependientes de H-1B trabajar legalmente en los Estados Unidos?"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8891\" class=\"elementor elementor-8891\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f08b81 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f08b81\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a201a3d\" data-id=\"a201a3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-01ddaed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01ddaed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ca5132\" data-id=\"5ca5132\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1215b58 elementor-widget elementor-widget-text-editor\" data-id=\"1215b58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><em>Dependientes H1B trabajan legalmente: <\/em><em>2 minutos de lectura<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9e71a elementor-widget elementor-widget-text-editor\" data-id=\"1f9e71a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Las visas H-1B se otorgan cada a\u00f1o en funci\u00f3n de una variedad de factores, y son un programa de visas que est\u00e1 estrictamente vinculado al empleo en empresas estadounidenses.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd29c4e elementor-widget elementor-widget-text-editor\" data-id=\"dd29c4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Es posible que sepa que los beneficiarios de <a href=\"https:\/\/loigica.com\/es\/visas-h1b\/\" target=\"_blank\" rel=\"noopener\">la visa H-1B<\/a> pueden viajar a los Estados Unidos para trabajar en un trabajo espec\u00edfico como parte de un contrato de trabajo. Lo que quiz\u00e1s no sepa es que sus dependientes familiares, es decir, los c\u00f3nyuges, pueden ingresar a los Estados Unidos con el destinatario de la visa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcaa041 elementor-widget elementor-widget-text-editor\" data-id=\"dcaa041\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Teniendo en cuenta que el programa H-1B b\u00e1sicamente resulta en que estas personas y familias desarraiguen sus vidas para mudarse a los Estados Unidos, tiene sentido preguntar:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c8a836 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1c8a836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48385db elementor-widget elementor-widget-heading\" data-id=\"48385db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">\u00bfPueden los c\u00f3nyuges trabajar legalmente en los <br>Estados Unidos mientras viven aqu\u00ed?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8826713 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8826713\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90e6067 elementor-widget elementor-widget-text-editor\" data-id=\"90e6067\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">S\u00ed. Por ejemplo, los permisos de trabajo dependientes no se otorgan autom\u00e1ticamente como parte de la distribuci\u00f3n de visas H-1B.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f48f97 elementor-widget elementor-widget-text-editor\" data-id=\"3f48f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Las familias interesadas en solicitar los permisos de trabajo con su estado de dependiente, tambi\u00e9n conocido como visas H-4, primero deben establecer la elegibilidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b056901 elementor-widget elementor-widget-text-editor\" data-id=\"b056901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Tenga en cuenta que los hijos solteros menores de 21 a\u00f1os con estatus H-4 no son elegibles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-153e0df elementor-widget elementor-widget-text-editor\" data-id=\"153e0df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Su EAD ser\u00e1 v\u00e1lido mientras tenga el estado H-4, que a su vez depender\u00e1 del estado H1B de su familiar. El estatus H-1B dura 3 a\u00f1os iniciales, cuando sea elegible este podr\u00e1 extenderse a un total de 6 a\u00f1os.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d65f2b elementor-widget elementor-widget-text-editor\" data-id=\"2d65f2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Si se requiere que su c\u00f3nyuge renueve su visa H-1B, tambi\u00e9n se le pedir\u00e1 que renueve su visa H-4 y EAD.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7b71a7 elementor-widget elementor-widget-image\" data-id=\"d7b71a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"250\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-1-1024x320.png\" class=\"attachment-large size-large wp-image-8925\" alt=\"dependientes H1B trabajan legalmente\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-1-1024x320.png 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-1-300x94.png 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-1-768x240.png 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-1-1536x480.png 1536w, https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-1.png 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aacac3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7aacac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea58d28 elementor-widget elementor-widget-heading\" data-id=\"ea58d28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Requisitos para ser elegible para la autorizaci\u00f3n de empleo como dependiente H1B:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d40b9a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5d40b9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f12cde elementor-widget elementor-widget-text-editor\" data-id=\"8f12cde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul style=\"font-weight: 400;\"><li>Debe ser el c\u00f3nyuge de un trabajador no inmigrante H-1B.<\/li><li>Debe haber solicitado y se le ha otorgado el estatus de visa H-4.<\/li><li>El trabajador H-1B debe estar en camino de obtener una tarjeta verde, es decir, tener una Petici\u00f3n de Inmigrante aprobada para el formulario I-140<\/li><li>o se les ha concedido una extensi\u00f3n a su estatus H1B bajo las secciones 106 (a) y (b) de la Ley de Competitividad Estadounidense en el Siglo XXI (AC21).<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87e0ec4 elementor-widget elementor-widget-text-editor\" data-id=\"87e0ec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Como titular de una visa H-4, debe residir en los Estados Unidos en el momento de su solicitud de EAD.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf0efdb elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"cf0efdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/loigica.com\/es\/visas-h1b\/\" target=\"_blank\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\t\u00a1Conoce m\u00e1s sobre la visa H1B!\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-559332c\" data-id=\"559332c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2323fec she-header-yes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2323fec\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;transparent&quot;:&quot;yes&quot;,&quot;transparent_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;scroll_distance&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:60,&quot;sizes&quot;:[]},&quot;scroll_distance_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;scroll_distance_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;she_offset_top_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;she_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:0,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:0,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0a1d7f5\" data-id=\"0a1d7f5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5272280 elementor-widget elementor-widget-heading\" data-id=\"5272280\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suscr\u00edbase a nuestro bolet\u00edn<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-614a407 elementor-widget elementor-widget-text-editor\" data-id=\"614a407\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Todo sobre leyes de inmigraci\u00f3n, visas, noticias, entrevistas interesantes y m\u00e1s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a6b6eb elementor-widget elementor-widget-html\" data-id=\"6a6b6eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n\u00a0 hbspt.forms.create({\n\u00a0\u00a0\u00a0 region: \"na1\",\n\u00a0\u00a0\u00a0 portalId: \"1653096\",\n\u00a0\u00a0\u00a0 formId: \"d1ccf341-663b-47e5-8d14-dae72bccf2e3\"\n\u00a0 });\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c48d48 elementor-widget elementor-widget-heading\" data-id=\"3c48d48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recomendados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28a3747 elementor-grid-1 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"28a3747\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8893 post type-post status-publish format-standard has-post-thumbnail hentry category-inmigracion-familiar tag-greencard tag-peticion-familiar\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense.jpg\" class=\"attachment-full size-full wp-image-12162\" alt=\"\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense.jpg 1920w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-300x169.jpg 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-1024x576.jpg 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-768x432.jpg 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/\" >\n\t\t\t\t\u00bfPuede un ciudadano estadounidense patrocinar a un familiar extranjero?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tCamilo Espinosa\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tmayo 13, 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre \u00bfPuede un ciudadano estadounidense patrocinar a un familiar extranjero?\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8872 post type-post status-publish format-standard has-post-thumbnail hentry category-inmigracion-familiar tag-peticion-familiar tag-visa-k1\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/loigica.com\/es\/articulos-entrevista-visa-matrimonio\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024.jpg\" class=\"attachment-full size-full wp-image-12249\" alt=\"visas de matrimonio\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024.jpg 1920w, https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024-300x169.jpg 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024-1024x576.jpg 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024-768x432.jpg 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/loigica.com\/es\/articulos-entrevista-visa-matrimonio\/\" >\n\t\t\t\tConsejos para prepararse para su entrevista de visa de matrimonio\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tCamilo Espinosa\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tmayo 4, 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/loigica.com\/es\/articulos-entrevista-visa-matrimonio\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Consejos para prepararse para su entrevista de visa de matrimonio\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dependientes H1B trabajan legalmente: 2 minutos de lectura Las visas H-1B se otorgan cada a\u00f1o en funci\u00f3n de una variedad de factores, y son un<\/p>\n","protected":false},"author":6,"featured_media":12322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[101,100],"tags":[55,26],"class_list":["post-8891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmigracion-familiar","category-visas-trabajo-talento","tag-h1b","tag-h4-visa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trabajo para dependientes de visa H1B | LOIGICA Abogados de Inmigraci\u00f3n<\/title>\n<meta name=\"description\" content=\"Las visas H1B se otorgan cada a\u00f1o en funci\u00f3n de una variedad de factores. Conoce c\u00f3mo trabajar legalmente en Estados Unidos como dependiente. \u00a1Ingresa ya!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loigica.com\/es\/articulos-visa-h1b\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trabajo para dependientes de visa H1B | LOIGICA Abogados de Inmigraci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Las visas H1B se otorgan cada a\u00f1o en funci\u00f3n de una variedad de factores. Conoce c\u00f3mo trabajar legalmente en Estados Unidos como dependiente. \u00a1Ingresa ya!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loigica.com\/es\/articulos-visa-h1b\/\" \/>\n<meta property=\"og:site_name\" content=\"Loigica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loigica\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-07T14:21:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T16:27:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Harry Tapias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Loigica\" \/>\n<meta name=\"twitter:site\" content=\"@Loigica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Harry Tapias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/\"},\"author\":{\"name\":\"Harry Tapias\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/person\\\/60199b3dba6e1a5123d993e1c4950194\"},\"headline\":\"\u00bfPueden los dependientes de H-1B trabajar legalmente en los Estados Unidos?\",\"datePublished\":\"2023-04-07T14:21:29+00:00\",\"dateModified\":\"2026-01-27T16:27:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/\"},\"wordCount\":428,\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/dependientes-H1B-trabajan-legalmente.jpg\",\"keywords\":[\"H1B\",\"H4 visa\"],\"articleSection\":[\"Inmigraci\u00f3n Familiar\",\"Visas de Trabajo y Talento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/\",\"name\":\"Trabajo para dependientes de visa H1B | LOIGICA Abogados de Inmigraci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/dependientes-H1B-trabajan-legalmente.jpg\",\"datePublished\":\"2023-04-07T14:21:29+00:00\",\"dateModified\":\"2026-01-27T16:27:52+00:00\",\"description\":\"Las visas H1B se otorgan cada a\u00f1o en funci\u00f3n de una variedad de factores. Conoce c\u00f3mo trabajar legalmente en Estados Unidos como dependiente. \u00a1Ingresa ya!\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-visa-h1b\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/dependientes-H1B-trabajan-legalmente.jpg\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/dependientes-H1B-trabajan-legalmente.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"name\":\"Loigica\",\"description\":\"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM\",\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loigica.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\",\"name\":\"Loigica\",\"alternateName\":\"Loigica Immigration Attorneys\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"width\":369,\"height\":317,\"caption\":\"Loigica\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loigica\\\/\",\"https:\\\/\\\/x.com\\\/Loigica\",\"https:\\\/\\\/www.instagram.com\\\/loigica\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Loigica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/person\\\/60199b3dba6e1a5123d993e1c4950194\",\"name\":\"Harry Tapias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3de3200eaba241584b95b565400a364fc9373f8538da3c25a8061c63103c103b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3de3200eaba241584b95b565400a364fc9373f8538da3c25a8061c63103c103b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3de3200eaba241584b95b565400a364fc9373f8538da3c25a8061c63103c103b?s=96&d=mm&r=g\",\"caption\":\"Harry Tapias\"},\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/author\\\/harry-tapias-esq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trabajo para dependientes de visa H1B | LOIGICA Abogados de Inmigraci\u00f3n","description":"Las visas H1B se otorgan cada a\u00f1o en funci\u00f3n de una variedad de factores. Conoce c\u00f3mo trabajar legalmente en Estados Unidos como dependiente. \u00a1Ingresa ya!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/","og_locale":"es_ES","og_type":"article","og_title":"Trabajo para dependientes de visa H1B | LOIGICA Abogados de Inmigraci\u00f3n","og_description":"Las visas H1B se otorgan cada a\u00f1o en funci\u00f3n de una variedad de factores. Conoce c\u00f3mo trabajar legalmente en Estados Unidos como dependiente. \u00a1Ingresa ya!","og_url":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/","og_site_name":"Loigica","article_publisher":"https:\/\/www.facebook.com\/loigica\/","article_published_time":"2023-04-07T14:21:29+00:00","article_modified_time":"2026-01-27T16:27:52+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente.jpg","type":"image\/jpeg"}],"author":"Harry Tapias","twitter_card":"summary_large_image","twitter_creator":"@Loigica","twitter_site":"@Loigica","twitter_misc":{"Escrito por":"Harry Tapias","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/#article","isPartOf":{"@id":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/"},"author":{"name":"Harry Tapias","@id":"https:\/\/loigica.com\/es\/#\/schema\/person\/60199b3dba6e1a5123d993e1c4950194"},"headline":"\u00bfPueden los dependientes de H-1B trabajar legalmente en los Estados Unidos?","datePublished":"2023-04-07T14:21:29+00:00","dateModified":"2026-01-27T16:27:52+00:00","mainEntityOfPage":{"@id":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/"},"wordCount":428,"publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"image":{"@id":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente.jpg","keywords":["H1B","H4 visa"],"articleSection":["Inmigraci\u00f3n Familiar","Visas de Trabajo y Talento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/","url":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/","name":"Trabajo para dependientes de visa H1B | LOIGICA Abogados de Inmigraci\u00f3n","isPartOf":{"@id":"https:\/\/loigica.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/#primaryimage"},"image":{"@id":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente.jpg","datePublished":"2023-04-07T14:21:29+00:00","dateModified":"2026-01-27T16:27:52+00:00","description":"Las visas H1B se otorgan cada a\u00f1o en funci\u00f3n de una variedad de factores. Conoce c\u00f3mo trabajar legalmente en Estados Unidos como dependiente. \u00a1Ingresa ya!","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loigica.com\/es\/articulos-visa-h1b\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/articulos-visa-h1b\/#primaryimage","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente.jpg","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente.jpg","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/loigica.com\/es\/#website","url":"https:\/\/loigica.com\/es\/","name":"Loigica","description":"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM","publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loigica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loigica.com\/es\/#organization","name":"Loigica","alternateName":"Loigica Immigration Attorneys","url":"https:\/\/loigica.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","width":369,"height":317,"caption":"Loigica"},"image":{"@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loigica\/","https:\/\/x.com\/Loigica","https:\/\/www.instagram.com\/loigica\/","https:\/\/www.youtube.com\/@Loigica\/"]},{"@type":"Person","@id":"https:\/\/loigica.com\/es\/#\/schema\/person\/60199b3dba6e1a5123d993e1c4950194","name":"Harry Tapias","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3de3200eaba241584b95b565400a364fc9373f8538da3c25a8061c63103c103b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3de3200eaba241584b95b565400a364fc9373f8538da3c25a8061c63103c103b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3de3200eaba241584b95b565400a364fc9373f8538da3c25a8061c63103c103b?s=96&d=mm&r=g","caption":"Harry Tapias"},"url":"https:\/\/loigica.com\/es\/author\/harry-tapias-esq\/"}]}},"_links":{"self":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/8891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/comments?post=8891"}],"version-history":[{"count":18,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/8891\/revisions"}],"predecessor-version":[{"id":11352,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/8891\/revisions\/11352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media\/12322"}],"wp:attachment":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media?parent=8891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/categories?post=8891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/tags?post=8891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}