{"id":8893,"date":"2023-05-13T10:22:35","date_gmt":"2023-05-13T14:22:35","guid":{"rendered":"https:\/\/loigica.com\/es\/?p=8893"},"modified":"2026-01-27T11:25:37","modified_gmt":"2026-01-27T16:25:37","slug":"articulos-residencia-permanente-familiares","status":"publish","type":"post","link":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/","title":{"rendered":"\u00bfPuede un ciudadano estadounidense patrocinar a un familiar extranjero?"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8893\" class=\"elementor elementor-8893\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f08b81 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f08b81\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a201a3d\" data-id=\"a201a3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-01ddaed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01ddaed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ca5132\" data-id=\"5ca5132\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1215b58 elementor-widget elementor-widget-text-editor\" data-id=\"1215b58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><em>Patrocinador ciudadano estadounidense<\/em><em>: 3 minutos de lectura.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9e71a elementor-widget elementor-widget-text-editor\" data-id=\"1f9e71a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Hay varios beneficios que los extranjeros disfrutan cuando pasan por la naturalizaci\u00f3n y se convierten en ciudadanos estadounidenses. Uno de esos beneficios es que pueden solicitar a los miembros de la familia que viven en el extranjero como extranjeros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0698dc elementor-widget elementor-widget-text-editor\" data-id=\"c0698dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Como ciudadano de los Estados Unidos, <strong>puedes ayudar a un pariente a convertirse en un residente permanente legal de los Estados Unidos por medio de una tarjeta verde.<\/strong> \u00a0Sin embargo, hay algunas cosas a tener en cuenta si decides embarcarte en este viaje, tales como:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd29c4e elementor-widget elementor-widget-text-editor\" data-id=\"dd29c4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Poder demostrar que tienes suficientes ingresos o activos para mantener a tu(s) pariente(s) cuando vengan a los Estados Unidos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcaa041 elementor-widget elementor-widget-text-editor\" data-id=\"dcaa041\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Solo puedes patrocinar a familiares inmediatos como:<\/p><ul style=\"font-weight: 400;\"><li>Tu c\u00f3nyuge<\/li><li>Tus hijos<\/li><li>Si tienes m\u00e1s de 21 a\u00f1os, puedes patrocinar a tus padres, hermanos o hermanas.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3978d3d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3978d3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bde733 elementor-widget elementor-widget-heading\" data-id=\"0bde733\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Comprender los pasos en el proceso de patrocinio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-466a7a8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"466a7a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90e6067 elementor-widget elementor-widget-text-editor\" data-id=\"90e6067\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Deber\u00e1s presentar un I-130, Petici\u00f3n para pariente extranjero. Este formulario establece la relaci\u00f3n familiar que existe entre t\u00fa y tu familiar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db362f4 elementor-widget elementor-widget-text-editor\" data-id=\"db362f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Tambi\u00e9n se puede presentar con la solicitud de residencia permanente (Formulario I-485, Solicitud de Registro de Residencia Permanente o Ajuste de Estatus).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19201dd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"19201dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9792d3 elementor-widget elementor-widget-heading\" data-id=\"f9792d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Re\u00fane evidencia de tu relaci\u00f3n.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e31c733 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e31c733\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f12cde elementor-widget elementor-widget-text-editor\" data-id=\"8f12cde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Cuando presentes tu petici\u00f3n, debes proporcionar evidencia para probar tu relaci\u00f3n con la persona para la que est\u00e1s presentando.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87e0ec4 elementor-widget elementor-widget-text-editor\" data-id=\"87e0ec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Una vez que se aprueben la solicitud y la relaci\u00f3n, estar\u00e1n en la cola para otros extranjeros que est\u00e9n en la misma categor\u00eda que ellos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72accf3 elementor-widget elementor-widget-text-editor\" data-id=\"72accf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Por ejemplo, un padre de un ciudadano estadounidense que vive en el extranjero se alinear\u00e1 con otros padres que esperan el patrocinio de su hijo patrocinador, el ciudadano estadounidense.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0045d7b elementor-widget elementor-widget-text-editor\" data-id=\"0045d7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Por lo general, cuando el pariente solicitado llega al frente de la fila en su categor\u00eda, puede presentar un formulario adicional para traer a su c\u00f3nyuge o cualquier hijo soltero junto con ellos. Un <a href=\"https:\/\/loigica.com\/es\/acerca-de-loigica\/nuestros-abogados\/\" target=\"_blank\" rel=\"noopener\">abogado de inmigraci\u00f3n<\/a> puede ayudar a explicar estos pasos y c\u00f3mo llevar a cabo este proceso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0539248 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0539248\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b123ae6 elementor-widget elementor-widget-heading\" data-id=\"b123ae6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Re\u00fane evidencia de tu relaci\u00f3n.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb473ec elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cb473ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7ebb2d elementor-widget elementor-widget-text-editor\" data-id=\"a7ebb2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Presentar cuando antes la petici\u00f3n de tu familiar ser\u00e1 lo ideal. Los tiempos de procesamiento actuales se pueden encontrar en <a href=\"http:\/\/www.uscis.gov\/\">www.uscis.gov<\/a>. Es una forma directa de monitorear el progreso de su petici\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d56018 elementor-widget elementor-widget-text-editor\" data-id=\"4d56018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Mientras te sometes a este proceso, tu familiar no puede ingresar prematuramente a los Estados Unidos con la esperanza de poder quedarse. Tu pariente debe permanecer en el extranjero y esperar para inmigrar legalmente a los Estados Unidos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be88037 elementor-widget elementor-widget-text-editor\" data-id=\"be88037\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Si t\u00fa eres un ciudadano estadounidense que busca <a href=\"https:\/\/www.uscis.gov\/sites\/default\/files\/document\/guides\/A1en.pdf\">solicitar un miembro<\/a> de la familia a los Estados Unidos, comun\u00edcate con nuestros abogados de inmigraci\u00f3n con experiencia para una consulta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7b71a7 elementor-widget elementor-widget-image\" data-id=\"d7b71a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"250\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-1-1024x320.png\" class=\"attachment-large size-large wp-image-8982\" alt=\"Patrocinador ciudadano estadounidense\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-1-1024x320.png 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-1-300x94.png 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-1-768x240.png 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-1-1536x480.png 1536w, https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense-1.png 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce57cc1 elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"ce57cc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/loigica.com\/es\/contactar\/\" target=\"_blank\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\t\u00a1Consulta ahora con un abogado!\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-559332c\" data-id=\"559332c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2323fec she-header-yes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2323fec\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;transparent&quot;:&quot;yes&quot;,&quot;transparent_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;scroll_distance&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:60,&quot;sizes&quot;:[]},&quot;scroll_distance_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;scroll_distance_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;she_offset_top_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;she_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:0,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:0,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0a1d7f5\" data-id=\"0a1d7f5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5272280 elementor-widget elementor-widget-heading\" data-id=\"5272280\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suscr\u00edbase a nuestro bolet\u00edn<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-614a407 elementor-widget elementor-widget-text-editor\" data-id=\"614a407\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Todo sobre leyes de inmigraci\u00f3n, visas, noticias, entrevistas interesantes y m\u00e1s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a6b6eb elementor-widget elementor-widget-html\" data-id=\"6a6b6eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n\u00a0 hbspt.forms.create({\n\u00a0\u00a0\u00a0 region: \"na1\",\n\u00a0\u00a0\u00a0 portalId: \"1653096\",\n\u00a0\u00a0\u00a0 formId: \"d1ccf341-663b-47e5-8d14-dae72bccf2e3\"\n\u00a0 });\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c48d48 elementor-widget elementor-widget-heading\" data-id=\"3c48d48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recomendados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28a3747 elementor-grid-1 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"28a3747\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8872 post type-post status-publish format-standard has-post-thumbnail hentry category-inmigracion-familiar tag-peticion-familiar tag-visa-k1\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/loigica.com\/es\/articulos-entrevista-visa-matrimonio\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024.jpg\" class=\"attachment-full size-full wp-image-12249\" alt=\"visas de matrimonio\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024.jpg 1920w, https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024-300x169.jpg 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024-1024x576.jpg 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024-768x432.jpg 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/blog_web_visas_matrimonio_26_03_2024-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/loigica.com\/es\/articulos-entrevista-visa-matrimonio\/\" >\n\t\t\t\tConsejos para prepararse para su entrevista de visa de matrimonio\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tCamilo Espinosa\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tmayo 4, 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/loigica.com\/es\/articulos-entrevista-visa-matrimonio\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Consejos para prepararse para su entrevista de visa de matrimonio\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8891 post type-post status-publish format-standard has-post-thumbnail hentry category-inmigracion-familiar category-visas-trabajo-talento tag-h1b tag-h4-visa\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/loigica.com\/es\/articulos-visa-h1b\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente.jpg\" class=\"attachment-full size-full wp-image-12322\" alt=\"\" srcset=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente.jpg 1920w, https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-300x169.jpg 300w, https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-1024x576.jpg 1024w, https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-768x432.jpg 768w, https:\/\/loigica.com\/es\/wp-content\/uploads\/dependientes-H1B-trabajan-legalmente-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/loigica.com\/es\/articulos-visa-h1b\/\" >\n\t\t\t\t\u00bfPueden los dependientes de H-1B trabajar legalmente en los Estados Unidos?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-author\">\n\t\t\tHarry Tapias\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tabril 7, 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/loigica.com\/es\/articulos-visa-h1b\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre \u00bfPueden los dependientes de H-1B trabajar legalmente en los Estados Unidos?\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Patrocinador ciudadano estadounidense: 3 minutos de lectura. Hay varios beneficios que los extranjeros disfrutan cuando pasan por la naturalizaci\u00f3n y se convierten en ciudadanos estadounidenses.<\/p>\n","protected":false},"author":5,"featured_media":12162,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[101],"tags":[36,71],"class_list":["post-8893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmigracion-familiar","tag-greencard","tag-peticion-familiar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Residencia para familiares en USA | LOIGICA Abogados de Inmigraci\u00f3n<\/title>\n<meta name=\"description\" content=\"Como ciudadano de los Estados Unidos puedes ayudar a un familiar a solicitar la residencia permanente. \u00a1Conoce m\u00e1s informaci\u00f3n de la green card aqu\u00ed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Residencia para familiares en USA | LOIGICA Abogados de Inmigraci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Como ciudadano de los Estados Unidos puedes ayudar a un familiar a solicitar la residencia permanente. \u00a1Conoce m\u00e1s informaci\u00f3n de la green card aqu\u00ed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/\" \/>\n<meta property=\"og:site_name\" content=\"Loigica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loigica\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-13T14:22:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T16:25:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Camilo Espinosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Loigica\" \/>\n<meta name=\"twitter:site\" content=\"@Loigica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camilo Espinosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/\"},\"author\":{\"name\":\"Camilo Espinosa\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/person\\\/7513b47226d48ec32034cb6e37c585c3\"},\"headline\":\"\u00bfPuede un ciudadano estadounidense patrocinar a un familiar extranjero?\",\"datePublished\":\"2023-05-13T14:22:35+00:00\",\"dateModified\":\"2026-01-27T16:25:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/\"},\"wordCount\":481,\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/Patrocinador-ciudadano-estadounidense.jpg\",\"keywords\":[\"greencard\",\"Petici\u00f3n Familiar\"],\"articleSection\":[\"Inmigraci\u00f3n Familiar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/\",\"name\":\"Residencia para familiares en USA | LOIGICA Abogados de Inmigraci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/Patrocinador-ciudadano-estadounidense.jpg\",\"datePublished\":\"2023-05-13T14:22:35+00:00\",\"dateModified\":\"2026-01-27T16:25:37+00:00\",\"description\":\"Como ciudadano de los Estados Unidos puedes ayudar a un familiar a solicitar la residencia permanente. \u00a1Conoce m\u00e1s informaci\u00f3n de la green card aqu\u00ed!\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/articulos-residencia-permanente-familiares\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/Patrocinador-ciudadano-estadounidense.jpg\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/Patrocinador-ciudadano-estadounidense.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"name\":\"Loigica\",\"description\":\"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM\",\"publisher\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loigica.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#organization\",\"name\":\"Loigica\",\"alternateName\":\"Loigica Immigration Attorneys\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"contentUrl\":\"https:\\\/\\\/loigica.com\\\/es\\\/wp-content\\\/uploads\\\/cropped-Loigica-Silver.png\",\"width\":369,\"height\":317,\"caption\":\"Loigica\"},\"image\":{\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/loigica\\\/\",\"https:\\\/\\\/x.com\\\/Loigica\",\"https:\\\/\\\/www.instagram.com\\\/loigica\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Loigica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loigica.com\\\/es\\\/#\\\/schema\\\/person\\\/7513b47226d48ec32034cb6e37c585c3\",\"name\":\"Camilo Espinosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g\",\"caption\":\"Camilo Espinosa\"},\"url\":\"https:\\\/\\\/loigica.com\\\/es\\\/author\\\/camilo-espinosa-esq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Residencia para familiares en USA | LOIGICA Abogados de Inmigraci\u00f3n","description":"Como ciudadano de los Estados Unidos puedes ayudar a un familiar a solicitar la residencia permanente. \u00a1Conoce m\u00e1s informaci\u00f3n de la green card aqu\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/","og_locale":"es_ES","og_type":"article","og_title":"Residencia para familiares en USA | LOIGICA Abogados de Inmigraci\u00f3n","og_description":"Como ciudadano de los Estados Unidos puedes ayudar a un familiar a solicitar la residencia permanente. \u00a1Conoce m\u00e1s informaci\u00f3n de la green card aqu\u00ed!","og_url":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/","og_site_name":"Loigica","article_publisher":"https:\/\/www.facebook.com\/loigica\/","article_published_time":"2023-05-13T14:22:35+00:00","article_modified_time":"2026-01-27T16:25:37+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense.jpg","type":"image\/jpeg"}],"author":"Camilo Espinosa","twitter_card":"summary_large_image","twitter_creator":"@Loigica","twitter_site":"@Loigica","twitter_misc":{"Escrito por":"Camilo Espinosa","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/#article","isPartOf":{"@id":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/"},"author":{"name":"Camilo Espinosa","@id":"https:\/\/loigica.com\/es\/#\/schema\/person\/7513b47226d48ec32034cb6e37c585c3"},"headline":"\u00bfPuede un ciudadano estadounidense patrocinar a un familiar extranjero?","datePublished":"2023-05-13T14:22:35+00:00","dateModified":"2026-01-27T16:25:37+00:00","mainEntityOfPage":{"@id":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/"},"wordCount":481,"publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"image":{"@id":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense.jpg","keywords":["greencard","Petici\u00f3n Familiar"],"articleSection":["Inmigraci\u00f3n Familiar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/","url":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/","name":"Residencia para familiares en USA | LOIGICA Abogados de Inmigraci\u00f3n","isPartOf":{"@id":"https:\/\/loigica.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/#primaryimage"},"image":{"@id":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/#primaryimage"},"thumbnailUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense.jpg","datePublished":"2023-05-13T14:22:35+00:00","dateModified":"2026-01-27T16:25:37+00:00","description":"Como ciudadano de los Estados Unidos puedes ayudar a un familiar a solicitar la residencia permanente. \u00a1Conoce m\u00e1s informaci\u00f3n de la green card aqu\u00ed!","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/articulos-residencia-permanente-familiares\/#primaryimage","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense.jpg","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/Patrocinador-ciudadano-estadounidense.jpg","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/loigica.com\/es\/#website","url":"https:\/\/loigica.com\/es\/","name":"Loigica","description":"Abogados de Negocios e Inmigraci\u00f3n | USA - LATAM","publisher":{"@id":"https:\/\/loigica.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loigica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loigica.com\/es\/#organization","name":"Loigica","alternateName":"Loigica Immigration Attorneys","url":"https:\/\/loigica.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","contentUrl":"https:\/\/loigica.com\/es\/wp-content\/uploads\/cropped-Loigica-Silver.png","width":369,"height":317,"caption":"Loigica"},"image":{"@id":"https:\/\/loigica.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loigica\/","https:\/\/x.com\/Loigica","https:\/\/www.instagram.com\/loigica\/","https:\/\/www.youtube.com\/@Loigica\/"]},{"@type":"Person","@id":"https:\/\/loigica.com\/es\/#\/schema\/person\/7513b47226d48ec32034cb6e37c585c3","name":"Camilo Espinosa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a3c9b215b6c1fcc750e773ff08ec8d17a18b954109f601d8c4fc9cabf92c5c0?s=96&d=mm&r=g","caption":"Camilo Espinosa"},"url":"https:\/\/loigica.com\/es\/author\/camilo-espinosa-esq\/"}]}},"_links":{"self":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/8893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/comments?post=8893"}],"version-history":[{"count":11,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/8893\/revisions"}],"predecessor-version":[{"id":11350,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/posts\/8893\/revisions\/11350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media\/12162"}],"wp:attachment":[{"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/media?parent=8893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/categories?post=8893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loigica.com\/es\/wp-json\/wp\/v2\/tags?post=8893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}